{"id":35484,"date":"2014-08-16T04:10:00","date_gmt":"2014-08-16T02:10:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/farmaci-in-estate-consigli-per-utilizzare-i-medicinali-in-sicurezza\/"},"modified":"2023-01-17T12:57:41","modified_gmt":"2023-01-17T11:57:41","slug":"15481-farmaci-in-estate-consigli-per-utilizzare-i-medicinali-in-sicurezza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15481-farmaci-in-estate-consigli-per-utilizzare-i-medicinali-in-sicurezza\/","title":{"rendered":"Farmaci in estate, consigli per utilizzare i medicinali in sicurezza"},"content":{"rendered":"<p>ROMA &#8211;&nbsp;&#8220;Perch\u00e9 la sicurezza\u2026non va in vacanza!&#8221; e&#8217; questo lo slogan coniato dall&#8217;AIFA per presentare le 20 facili regole da osservare per la conservazione, il trasporto e l\u2019assunzione dei medicinali durante l\u2019estate.<\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 11.818181991577148px;\">L&#8217;Agenzia Italiana del Farmaco (AIFA) ha redatto un \u201cventalogo\u201d che raccoglie precauzioni e consigli utili per utilizzare i farmaci in maniera corretta.<\/span>&nbsp;Ma vediamo nel dettaglio:<\/p>\n<p>&nbsp;<\/p>\n<p>1. Qualora l\u2019aspetto del medicinale che si utilizza abitualmente appaia diverso dal solito o presenti dei difetti (presenza di particelle solide in sospensione o sul fondo, cambio di colore o odore, modifica di consistenza), consulta il medico o il farmacista prima di assumerlo. <strong>Non assumerlo se hai dubbi sull\u2019integrit\u00e0 del prodotto.<\/strong> Segnala al medico qualsiasi malessere, anche lieve, in concomitanza con una terapia farmacologica, perch\u00e9 non tutti i farmaci possono avere effetti facilmente correlabili al caldo.<\/p>\n<p>&nbsp;<\/p>\n<p>2. Nel caso di un farmaco presente in diverse forme farmaceutiche e in assenza di specifiche controindicazioni (ad esempio la difficolt\u00e0 di deglutizione), s<strong>ono preferibili le formulazioni solide rispetto a quelle liquide<\/strong> che, contenendo acqua, sono in genere maggiormente sensibili alle alte temperature (termolabili).<\/p>\n<p>&nbsp;<\/p>\n<p>3. Per essere certo di conservare il medicinale nel modo corretto, leggi attentamente le modalit\u00e0 di conservazione indicate nelle informazioni del prodotto. Qualora queste non siano specificate, <strong>conserva il medicinale in luogo fresco e asciutto a una temperatura inferiore ai 25\u00b0<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>4. Nel caso non sia possibile conservarlo in frigo e, in caso di viaggi o soggiorni fuori casa, trasportalo in un contenitore termico. Agenti atmosferici come eccessiva luce e\/o sbalzi di temperatura possono infatti deteriorare i medicinali. <strong>Evita sempre, comunque, di esporli a fonti di calore e a irradiazione solare diretta.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>5. Se esponi i medicinali per un tempo esiguo (una o due giornate) a temperature superiori a 25\u00b0 non ne pregiudichi la qualit\u00e0, ma, per un tempo pi\u00f9 lungo, ne riduci considerevolmente la data di scadenza. <strong>Se invece la temperatura di conservazione \u00e8 specificatamente indicata, non rispettarla potrebbe addirittura renderli dannosi per la salute. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>6. Evita l\u2019uso di contenitori (portapillole) non esplicitamente destinati al trasporto di farmaci, in quanto potrebbero facilmente surriscaldarsi o rilasciare sostanze nocive ed alterare cos\u00ec le caratteristiche del medicinale.<strong> Estrai dal contenitore originale (flacone, blister, etc) solo la dose destinata alla somministrazione quotidiana.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>7.<strong>Se acquisti farmaci, non tenerli per ore in auto al caldo e portali a casa appena puoi.<\/strong> Se hai bisogno di conservare i medicinali di emergenza in auto, chiedi al tuo farmacista di consigliarti un contenitore sicuro che ti consentir\u00e0 di mantenere il farmaco alla corretta temperatura. Anche farmaci comuni possono produrre effetti potenzialmente dannosi se esposti a temperature troppo elevate.<\/p>\n<p>&nbsp;<\/p>\n<p>8. Se soffri di una patologia cronica come il diabete o di una malattia cardiaca, un\u2019alterazione di una dose di un farmaco fondamentale, come l&#8217;insulina o la nitroglicerina, pu\u00f2 essere rischiosa. <strong>Ricorda che i farmaci a base di insulina vanno conservati in frigorifero.<\/strong> In caso di lunghi viaggi o se hai necessit\u00e0 di tenerli in auto per emergenza, conservali in un contenitore sicuro che li mantenga alla giusta temperatura. Presta particolare attenzione anche con gli antiepilettici e gli anticoagulanti. Piccole modificazioni in farmaci come questi possono fare una grande differenza per la tua salute.<strong> Alcune alterazioni che potrebbero verificarsi in antibiotici e\/o aspirina potrebbero causare danni ai reni o allo stomaco.<\/strong> Ma non \u00e8 tutto: una crema a base di idrocortisone, ad esempio, per effetto del calore potrebbe separarsi nei suoi componenti e perdere di efficacia.<\/p>\n<p>&nbsp;<\/p>\n<p>9. Se utilizzi farmaci in forma pressurizzata (spray), evitane l\u2019esposizione al sole o a temperature elevate e utilizza contenitori termici per il trasporto.<\/p>\n<p>&nbsp;<\/p>\n<p>10. Qualsiasi tipo di striscia per test diagnostici, come ad esempio quelle utilizzate per verificare i livelli di zucchero nel sangue, la gravidanza o l\u2019ovulazione, \u00e8 estremamente sensibile all&#8217;umidit\u00e0, che potrebbe causarne l\u2019alterazione e dare una lettura non corretta. Evita di conservarle in luoghi umidi o eccessivamente caldi.<\/p>\n<p>&nbsp;<\/p>\n<p>11.<strong> I farmaci per la tiroide, i contraccettivi e altri medicinali che contengono ormoni sono particolarmente sensibili alle variazioni termich<\/strong>e. Questi sono a volte a base di proteine, che per effetto del calore cambiano propriet\u00e0. Anche in questo caso conservali in ambienti freschi e a temperatura costante.<\/p>\n<p>&nbsp;<\/p>\n<p>12. Sebbene sia difficile immaginare temperature di congelamento in piena estate, tieni presente che <strong>anche il freddo eccessivo pu\u00f2 causare alterazioni dei farmaci.<\/strong> L&#8217;insulina, ad esempio cos\u00ec come i farmaci in sospensione, possono perdere la loro efficacia se congelati. Non conservali a temperature inferiori ai 2\u00b0 C.<\/p>\n<p>&nbsp;<\/p>\n<p>13. <strong>Non inserire farmaci diversi in una sola confezione e non mescolarli in uno stesso contenitore per risparmiare spazio in val<\/strong>igia: potresti avere poi delle difficolt\u00e0 a riconoscere la data di scadenza, la tipologia del medicinale e il dosaggio.<\/p>\n<p>&nbsp;<\/p>\n<p>14. Se devi affrontare un lungo viaggio in auto, trasporta i farmaci nell\u2019abitacolo condizionato e\/o in un contenitore termico. Evita invece il bagagliaio che potrebbe surriscaldarsi eccessivamente.<\/p>\n<p>&nbsp;<\/p>\n<p>15. <strong>Durante il viaggio in aereo, colloca i farmaci nel bagaglio a mano.<\/strong> In caso di flaconi liquidi di medicinali gi\u00e0 aperti, mantienili in posizione verticale. Se sei in terapia con farmaci salvavita porta in cabina tali medicinali con le relative ricette di prescrizione, poich\u00e9 potrebbe essere necessario esibirle nelle fasi di controllo. 1<\/p>\n<p>&nbsp;<\/p>\n<p>6. Se devi necessariamente spedire dei medicinali scegli sempre le compresse o comunque forme solide.<\/p>\n<p>&nbsp;<\/p>\n<p>17. Alcuni farmaci possono causare reazioni da fotosensibilizzazione (reazioni fototossiche o fotoallergiche che solitamente sono costituite da manifestazioni cutanee come dermatiti, eczemi, ecc.) a seguito dell\u2019esposizione al sole. Controlla attentamente le istruzioni in caso di assunzione di: antibiotici (tetracicline, chinolonici), sulfamidici, contraccettivi orali (pillola), antinfiammatori non steroidei (FANS), prometazina (antistaminico).<\/p>\n<p>&nbsp;<\/p>\n<p>18. <strong>Evita l\u2019esposizione al sole dopo l\u2019applicazione di gel\/cerotti a base di ketoprofene<\/strong> <strong>(fino a due settimane dopo il trattamento<\/strong>) o creme a base di prometazina, queste ultime spesso utilizzate per le punture di insetti o allergie cutanee; in caso lava accuratamente la zona interessata, in modo da evitare la comparsa di macchie o, peggio, vere e proprie ustioni. Per tutti gli altri medicinali in forma di gel\/crema verificane la compatibilit\u00e0 con l\u2019esposizione al sole.<\/p>\n<p>&nbsp;<\/p>\n<p>19. Il caldo pu\u00f2 provocare l\u2019abbassamento della pressione anche in soggetti ipertesi, pertanto la<strong> terapia dell\u2019ipertensione arteriosa<\/strong> (ACE inibitori in associazione o meno con diuretici, sartani, calcio antagonisti, diuretici, beta bloccanti, bloccanti dei recettori alfa adrenergici) e di altre malattie cardiovascolari potrebbe richiedere un riadattamento da parte del medico\/specialista nel periodo estivo. E&#8217; opportuno, inoltre, effettuare un controllo pi\u00f9 assiduo della pressione arteriosa.<\/p>\n<p>&nbsp;<\/p>\n<p>20. Intorno agli occhi, nel periodo estivo, <strong>non utilizzare prodotti che con il calore potrebbero entrare a contatto con la superficie oculare<\/strong> (creme o pomate non idonee all\u2019uso oftalmico).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211;&nbsp;&#8220;Perch\u00e9 la sicurezza\u2026non va in vacanza!&#8221; e&#8217; questo lo slogan coniato dall&#8217;AIFA per presentare le 20 facili regole da osservare per la conservazione, il trasporto e l\u2019assunzione dei medicinali durante l\u2019estate.<\/p>\n","protected":false},"author":22,"featured_media":35485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-35484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35484"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35485"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}