{"id":35502,"date":"2014-08-14T07:58:53","date_gmt":"2014-08-14T05:58:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/quattordicenne-attraversa-i-binari-e-viene-ucciso-da-un-treno-in-corsa\/"},"modified":"2023-01-17T12:57:42","modified_gmt":"2023-01-17T11:57:42","slug":"15491-quattordicenne-attraversa-i-binari-e-viene-ucciso-da-un-treno-in-corsa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15491-quattordicenne-attraversa-i-binari-e-viene-ucciso-da-un-treno-in-corsa\/","title":{"rendered":"Quattordicenne attraversa i binari e viene ucciso da un treno in corsa"},"content":{"rendered":"<p>CALOPEZZATI (CS) &#8211; I sanitari non hanno potuto far altro se non constatare l&#8217;avvenuto decesso.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Vincenzo Donnici, di Calopezzati, \u00e8 morto ieri sera dopo essere stato investito da un treno.&nbsp;L&#8217;incidente \u00e8 avvenuto in un tratto della linea ferroviaria dove non ci sono passaggi a livello, vicino ad un campetto di calcio. Il ragazzino, secondo una prima ricostruzione dei carabinieri, ha attraversato i binari, forse di ritorno dal campo, senza accorgersi dell&#8217;arrivo del treno locale che lo ha travolto. I medici del 118 hanno cercato di rianimarlo sul posto, ma inutilmente. Vincenzo \u00e8 morto prima di poter essere portato in ospedale. I genitori del ragazzino sono entrambi medici. La madre \u00e8 una geriatra ed il padre \u00e8 a capo del distretto sanitario di Calopezzati.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CALOPEZZATI (CS) &#8211; I sanitari non hanno potuto far altro se non constatare l&#8217;avvenuto decesso.<\/p>\n","protected":false},"author":22,"featured_media":35503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35502"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35503"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}