{"id":35504,"date":"2014-08-14T08:08:09","date_gmt":"2014-08-14T06:08:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-cibo-e-pessimo-gli-ospiti-del-villaggio-protestano-sino-all-arrivo-dei-militatri\/"},"modified":"2023-01-17T12:57:42","modified_gmt":"2023-01-17T11:57:42","slug":"15492-il-cibo-e-pessimo-gli-ospiti-del-villaggio-protestano-sino-all-arrivo-dei-militatri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15492-il-cibo-e-pessimo-gli-ospiti-del-villaggio-protestano-sino-all-arrivo-dei-militatri\/","title":{"rendered":"&#8216;Il cibo \u00e8 pessimo&#8217;, gli ospiti del villaggio protestano sino all&#8217;arrivo dei militari"},"content":{"rendered":"<p>ZAMBRONE (VIV) &#8211; Per sedare la rivolta dei turisti \u00e8 stato necessario l&#8217;intervento dei carabinieri.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Circa 200 ospiti di un villaggio turistico di marina di Zambrone hanno inscenato oggi una protesta contro la propriet\u00e0 della struttura ricettiva che li ospita. Alla base della sollevazione, secondo quanto si \u00e8 appreso, ci sarebbe la scarsa qualit\u00e0 del cibo e alcuni problemi di carattere logistico, in quanto la struttura ha aperto a fine luglio senza che fossero stati eseguiti in precedenza i lavori di manutenzione. La protesta \u00e8 stata sedata grazie all&#8217;intervento dei carabinieri e di tre pattuglie della polizia. Sul posto \u00e8 intervenuto personale dell&#8217;ufficio igiene dell&#8217;Asp di Vibo e i Vigili del fuoco per la messa in sicurezza di alcune strutture. Molti villeggianti, perlopi\u00f9 provenienti dalla Campania, hanno preferito andarsene nella speranza di trovare una sistemazione, cosa non facile per il periodo, mentre altri si sono visti costretti a rimanere proprio per la mancanza di praticabili alternative.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ZAMBRONE (VIV) &#8211; Per sedare la rivolta dei turisti \u00e8 stato necessario l&#8217;intervento dei carabinieri.<\/p>\n","protected":false},"author":22,"featured_media":35505,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-35504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35504"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35505"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}