{"id":35506,"date":"2014-08-14T08:10:31","date_gmt":"2014-08-14T06:10:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/ombrelloni\/"},"modified":"2023-01-17T12:57:42","modified_gmt":"2023-01-17T11:57:42","slug":"15493-ombrelloni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15493-ombrelloni\/","title":{"rendered":"Turisti lasciano ombrelloni in spiaggia per l&#8217;indomani, tutti sequestrati"},"content":{"rendered":"<p>ROCCELLA JONICA (RC) &#8211; La Guardia costiera ha sequestrato, a Roccella Jonica, 308 ombrelloni e 15 sdraio incustoditi.<\/p>\n<p>  <!--more-->  <\/p>\n<p>E&#8217; successo a Roccella Jonica, nel reggino, nei tratti di spiaggia libera vicino al lungomare. Il sequestro \u00e8 stato fatto in esecuzione di un&#8217;ordinanza comunale che fissa il divieto di lasciare, oltre il tramonto, sulle spiagge libere, ombrelloni, sdraio, tende e altre attrezzature. L&#8217;attivit\u00e0 della Guardia costiera rientra nell&#8217;ambito dell&#8217; operazione &#8220;Mare Sicuro 2014..<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROCCELLA JONICA (RC) &#8211; La Guardia costiera ha sequestrato, a Roccella Jonica, 308 ombrelloni e 15 sdraio incustoditi.<\/p>\n","protected":false},"author":22,"featured_media":35507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-35506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35506"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35507"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}