{"id":35584,"date":"2014-08-19T04:58:02","date_gmt":"2014-08-19T02:58:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-bagnino-non-e-al-suo-posto-multato-il-gestore-di-un-lido-a-fiumefreddo\/"},"modified":"2023-01-17T12:57:47","modified_gmt":"2023-01-17T11:57:47","slug":"15534-il-bagnino-non-e-al-suo-posto-multato-il-gestore-di-un-lido-a-fiumefreddo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15534-il-bagnino-non-e-al-suo-posto-multato-il-gestore-di-un-lido-a-fiumefreddo\/","title":{"rendered":"Il bagnino non \u00e8 al suo posto, multato il gestore di un lido a Fiumefreddo"},"content":{"rendered":"<p>FIUMEFREDDO (CS) &#8211; Il titolare del lido ha rimediato una sanzione amministrativa di 1.032 euro.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Gli uomini dell&#8217;Ufficio Circondariale Marittimo di Cetraro, impegnati in un&#8217;attivit\u00e0 di vigilanza dei litorali, hanno controllato un lido a Fiumefreddo Bruzio, sul tirreno cosentino e a seguito del blitz, hanno sorpreso il bagnino addetto al salvataggio fuori dalla sua postazione, nonostante diversi bagnanti fossero in acqua e numerose altre persone sulla spiaggia. Al titolare del lido e&#8217; stato comminato un verbale amministrativo di oltre mille euro, in quanto ritenuto responsabile di non aver attivato il servizio di assistenza e salvataggio, obbligatorio durante gli orari di apertura al pubblico delle strutture balneari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FIUMEFREDDO (CS) &#8211; Il titolare del lido ha rimediato una sanzione amministrativa di 1.032 euro.<\/p>\n","protected":false},"author":19,"featured_media":35585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35584"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35585"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}