{"id":35594,"date":"2014-08-19T05:57:00","date_gmt":"2014-08-19T03:57:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/ponte-trappola-sulla-ss-106-a-rischio-autisti-e-residenti-foto\/"},"modified":"2023-01-17T12:57:48","modified_gmt":"2023-01-17T11:57:48","slug":"15539-ponte-trappola-sulla-ss-106-a-rischio-autisti-e-residenti-foto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15539-ponte-trappola-sulla-ss-106-a-rischio-autisti-e-residenti-foto\/","title":{"rendered":"\u2018Ponte-trappola\u2019 sulla SS 106, a rischio autisti e residenti (FOTO)"},"content":{"rendered":"<p>AMENDOLARA (CS) \u2013 \u2018A piedi non si puo\u2019 andare, ti ammazzano i camion\u2019.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Lo sanno tutti quelli che abitano nel circondario. E non smettono di ripeterlo. A pochi metri dalle loro case ci sono negozi e bar, ma senza auto non ci si pu\u00f2 andare. N\u00e9 a Roseto, n\u00e9 ad Oriolo, n\u00e9 al mare perch\u00e9 c\u2019\u00e8 la ferrovia da attraversare. Anche in bici \u00e8 pericoloso. Auto e autocarri sfrecciano sfiorando il guardrail. La carreggiata del ponte che attraversa il fiume Ferro, al confine tra Amendolara e Roseto Capo Spulico, \u00e8 troppo stretta e non ci sono marciapiedi. Ci sono nelle nuove gallerie, a pochi chilometri di distanza, ma non sul ponte. L\u2019incubo di vivere a ridosso di un viadotto della \u2018statale della morte\u2019 tiene sotto scacco circa un centinaio di residenti. E tutti i camionisti che transitano in quel tratto di ss 106, costretti a fermarsi per far passare gli altri autotrasportatori per evitare cruenti scontri frontali.<\/p>\n<p>&nbsp;<\/p>\n<p>Il ponte, pare essere stato costruito senza prevedere che due camion, contemporaneamente, potessero attraversarlo in direzioni opposte. Non \u00e8 stato contemplato. \u201cL\u2019Anas un paio d\u2019anni fa ha fatto un sopralluogo per verificare la possibilit\u00e0 di allargare le carreggiata. Nel frattempo per\u00f2 si parla della costruzione di un altro tratto stradale \u2013 spiega uno degli abitanti del quartiere \u2013 ci vorranno almeno dieci anni e decine di morti finch\u00e8 la mettano in sicurezza\u201d. Di incidenti mortali nel tratto stradale al confine tra Amendolara e Roseto Capo Spulico se ne contano diversi. A perdere la vita: nel 2006 due tifosi catanesi Carmelo Ligreci e il ventenne Fabio Seminara in trasferta per il match che avrebbe potuto sancire l\u2019ascesa del Catania in A; nel 2009 un camionista trentenne alla guida di un furgone scontratosi con un autoarticolato; nel 2012 un 74enne a bordo di un\u2019Alfa Romeo schiantatasi contro un furgoncino tra Oriolo e Amendolara. Per ora, l&#8217;unico antidoto al &#8216;ponte\/trappola&#8217; resta il rallentare, sperando di non incrociare un camion. <\/p>\n<p>{imageshow sl=148 sc=3 \/}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AMENDOLARA (CS) \u2013 \u2018A piedi non si puo\u2019 andare, ti ammazzano i camion\u2019.<\/p>\n","protected":false},"author":18,"featured_media":35595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35594"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35595"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}