{"id":35618,"date":"2014-08-19T10:25:22","date_gmt":"2014-08-19T08:25:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/al-via-la-mostra-di-mimmo-rotella-all-interno-dell-ex-lazzaretto\/"},"modified":"2023-01-17T12:57:49","modified_gmt":"2023-01-17T11:57:49","slug":"15552-al-via-la-mostra-di-mimmo-rotella-all-interno-dell-ex-lazzaretto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15552-al-via-la-mostra-di-mimmo-rotella-all-interno-dell-ex-lazzaretto\/","title":{"rendered":"Al via la mostra di Mimmo Rotella all&#8217;interno dell&#8217;ex lazzaretto"},"content":{"rendered":"<p>CROTONE &#8211; E\u2019 stata inaugurata ieri sera sul lungomare di Crotone, la mostra di Mimmo Rotella.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Dodici opere del grande artista calabrese, che fanno parte della collezione privata di Flavio Lattuada, che sar\u00e0 possibile ammirare fino al 31 agosto nell\u2019ambito di una mostra promossa dall\u2019assessorato alla Cultura del Comune di Crotone e curata dal professor Antonio Maria Pivetta. L\u2019ex Lazzaretto torna a proporsi, dopo il successo della mostra dedicata al \u201cRigorismo\u201d, come galleria d\u2019arte ospitando uno degli artisti contemporanei pi\u00f9 apprezzati che ha lasciato un segno indelebile nel mondo dell\u2019arte. <strong>Opere che vanno dal 1958 al 2005 e che denotano la capacit\u00e0 di Rotella di \u201crapire le immagini\u201d e di darne una connotazione unica e personale. Nel corso della visita della mostra, curata nei particolari, si possono ammirare: \u201cPalinsesto\u201d (1958), \u201cVisi\u201d (1964-1990), \u201cL\u2019eterno Vagabondo\u201d (1965 \u2013 1999), \u201cLoren\u201d (1990), \u201cMarilyn Rock\u201d (1990); \u201cSensuale\u201d (1990); \u201cMarylin sensuale\u201d (1990); \u201cGuida\u201d (2000); \u201cLa grande cavalcata\u201d (2005); \u201cAlpha blu\u201d (2005); \u201cDeliziose\u201d (2005) e \u201cGuerra di Stelle\u201d (2005). <\/strong>Alla inaugurazione della mostra \u00e8 intervenuto il vice sindaco Mario Megna il quale ha sottolineato \u201cl\u2019omaggio che la citt\u00e0 di Crotone fa ad un grande artista calabrese conosciuto in tutto il mondo e la possibilit\u00e0 per il pubblico di poter visitare una mostra unica in un luogo che si presta idealmente ad ospitare la bellezza delle opere di Mimmo Rotella\u201d. <strong>La mostra \u00e8 aperta al pubblico tutti i giorni dalle 19.00 alle 23.00 fino al 31 agosto.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; E\u2019 stata inaugurata ieri sera sul lungomare di Crotone, la mostra di Mimmo Rotella.<\/p>\n","protected":false},"author":22,"featured_media":35619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-35618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35618"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35619"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}