{"id":35668,"date":"2014-08-21T04:04:44","date_gmt":"2014-08-21T02:04:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/anziana-gambizzata-nel-vibonese-e-mistero-sull-autore-del-ferimento\/"},"modified":"2023-01-17T12:58:02","modified_gmt":"2023-01-17T11:58:02","slug":"15577-anziana-gambizzata-nel-vibonese-e-mistero-sull-autore-del-ferimento","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15577-anziana-gambizzata-nel-vibonese-e-mistero-sull-autore-del-ferimento\/","title":{"rendered":"Anziana gambizzata nel Vibonese, \u00e8 mistero sull&#8217;autore del ferimento"},"content":{"rendered":"<p>MILETO (VV) &#8211; L&#8217;anziana vive da sola con il figlio, dopo averne perso un altro, vittima di lupara bianca nel 2005.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Ieri, il misterioso ferimento avvenuto nella&nbsp;frazione San Giovanni di Mileto, nel Vibonese. La ferita \u00e8 una donna di 78 anni, Giuseppina Pititto, che \u00e8 stata raggiunta da un colpo d&#8217;arma da fuoco alla gamba destra e che si \u00e8 presentata al pronto soccorso per farsi medicare la ferita. Ai carabinieri ha raccontato che si trovava all&#8217;esterno della sua abitazione intorno alle 8, ieri mattina quando \u00e8 stata raggiunta da un proiettile vagante. Gli investigatori per\u00f2 stanno verificando il racconto della donna ritenuto poco convincente.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MILETO (VV) &#8211; L&#8217;anziana vive da sola con il figlio, dopo averne perso un altro, vittima di lupara bianca nel 2005.<\/p>\n","protected":false},"author":19,"featured_media":35669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-35668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35668"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35669"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}