{"id":35676,"date":"2014-08-21T05:30:49","date_gmt":"2014-08-21T03:30:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/a-cetraro-l-edizione-2014-di-modamare-festival-nazionale-della-moda\/"},"modified":"2023-01-17T12:58:02","modified_gmt":"2023-01-17T11:58:02","slug":"15581-a-cetraro-l-edizione-2014-di-modamare-festival-nazionale-della-moda","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15581-a-cetraro-l-edizione-2014-di-modamare-festival-nazionale-della-moda\/","title":{"rendered":"A Cetraro l&#8217;edizione 2014 di &#8216;Modamare &#8211; Festival Nazionale della Moda&#8217;"},"content":{"rendered":"<p>CETRARO (CS) &#8211; Tutto pronto nella cittadina tirrenica per una serata all&#8217;insegna della moda e della musica, alla presenza di tanti prestigiosi ospiti.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u201cModamare \u2013 Festival Nazionale della Moda\u201d, si terr\u00e0 domani sera, <strong>venerd\u00ec 22 agosto, dalle 21.30<\/strong> nella splendida cornice del <strong>Porto di Cetraro<\/strong>. L&#8217;evento \u00e8 patrocinato dalla Regione Calabria, dalla Provincia di Cosenza e dall&#8217;Amministrazione comunale di Cetraro e organizzato dal Gruppo Monte Carlo, fin dalla prima edizione, sotto la direzione artistica di Giancarlo Zicarelli. Una kermesse originale che riscuote ogni anno il gradimento del pubblico e quest&#8217;anno dedicata al tempio della moda, l&#8217;affascinate isola di Capri. \u201cNon potevamo che rendere omaggio a Capri \u2013 spiega il direttore artistico Giancarlo Zicarelli \u2013 in questa meravigliosa isola nacque un vero e proprio feomeno italiano che afferm\u00f2 il made in Italy in tutto il mondo \u2013 e continua \u2013 Modamare, quest&#8217;anno, si ispirer\u00e0 a quelle atmosfere ai fasti e agli spledori di un&#8217;isola che influenz\u00f2 correnti artistiche e dett\u00f2 le mode dell&#8217;epoca\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Special guest della IXX edizione, una firma d\u2019autore della musica italiana, la talentuosa ragazza pugliese che si rivel\u00f2 al grande pubblico firmando una canzone per Gianni Morandi: <strong>Mariella Nava<\/strong>. Un vero e proprio omaggio alla canzone d&#8217;autore. Nava regaler\u00e0 al pubblico un medley dei sui brani pi\u00f9 celebri. Infine, le sar\u00e0 consegnato un Premio alla carriera. Ma le sorprese non finiscono qui, ancora tanta musica: direttamente da Chiambretti Supermarket la calda voce dell&#8217;affascinante <strong>Kelly Joyce<\/strong> e la frizzante e amatissima dal pubblico pi\u00f9 giovane Giorgia Mollo. \u201cModamare\u201d compie 19 anni collezionando un successo dopo l&#8217;altro. Nelle precedenti edizioni sono state numerose le presenze: Anna Tatangelo e Gigi D&#8217;Alessio; Toquinho, Loredana Bert\u00e8, Federica Panicucci, Peppino di Capri, Anna Safroncik, Lola Ponce, Renato Balestra e la pi\u00f9 recente partecipazione di Patty Pravo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CETRARO (CS) &#8211; Tutto pronto nella cittadina tirrenica per una serata all&#8217;insegna della moda e della musica, alla presenza di tanti prestigiosi ospiti.<\/p>\n","protected":false},"author":22,"featured_media":35677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35676"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35677"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}