{"id":35704,"date":"2014-08-21T12:04:51","date_gmt":"2014-08-21T10:04:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/e-se-all-expo-portassimo-il-codice-purpureo-invece-dei-bronzi\/"},"modified":"2023-01-17T12:58:03","modified_gmt":"2023-01-17T11:58:03","slug":"15595-e-se-all-expo-portassimo-il-codice-purpureo-invece-dei-bronzi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15595-e-se-all-expo-portassimo-il-codice-purpureo-invece-dei-bronzi\/","title":{"rendered":"E se all&#8217;Expo&#8217; portassimo il Codice Purpureo invece dei bronzi?"},"content":{"rendered":"<p>ROSSANO (CS) &#8211; La proposta lanciata dal Presidente della Pro Loco Rossano Federico Smurra.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il Codex Purpureus Rossanensis al centro del mondo per attrarre visitatori e turisti nella citt\u00e0 bizantina. Considerando la maggior consapevolezza, del valore tangibile ed immateriale del bene,&nbsp; percepito dalla comunit\u00e0 locale e dagli attori politici, ecclesiastici, sociali, culturali ed economici del territorio, sarebbe una mossa lungimirante cavalcare l\u2019onda della grande vetrina mondiale dell\u2019Exp\u00f2 che investir\u00e0 la Nazione nell\u2019anno 2015. &#8220;<strong>Esporre presso i padiglioni della vetrina mondiale, il preziosissimo evangelario, &#8211; afferma Smurra &#8211; gi\u00e0 inserito nell&#8217;elenco della Memory of the World dell&#8217;Unesco, possibilmente in copia e non con un\u2019azione isolata sarebbe una&nbsp; best practice di marketing, atta a riposizionare l\u2019immagine della localit\u00e0. L\u2019evento genererebbe importanti ricadute in termini di presenze turistiche per la nostra citt\u00e0 e per tutto il territorio.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019azione, per aver maggior forza propulsiva e di ricaduta in termini turistici sul territorio dovr\u00e0 essere ben concertata con tutti gli stakeholder, operatori del settore e dell\u2019indotto territoriali, accompagnata da una serie di iniziative e di servizi territoriali sia pubblici che privati, i quali dovranno culminare con l\u2019istituzione del grande evento Rossano Citt\u00e0 del Codex che si potrebbe collocare, temporalmente, in occasione dei festeggiamenti dell\u2019anno venturo del Santo Patrono Nilo o della Giornata Mondiale del Turismo tanto per restare a tema. <strong>Auspico che la proposta sia accolta positivamente dall\u2019 amministrazione civica e diocesana e, che si attivino sin da subito con i propri uffici deputati, a convocare gi\u00e0 nelle prossime settimane, una riunione concertativa con tutti gli attori portatori di interesse del territorio, per stabilire una road map delle attivit\u00e0 da intraprendere<\/strong>, perch\u00e9 come disse Sant\u2019Agostino \u201cio so cosa \u00e8 il tempo, ma quando me lo chiedono non so spiegarlo\u201d&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROSSANO (CS) &#8211; La proposta lanciata dal Presidente della Pro Loco Rossano Federico Smurra.<\/p>\n","protected":false},"author":22,"featured_media":35705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35704"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35705"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}