{"id":35718,"date":"2014-08-22T06:37:30","date_gmt":"2014-08-22T04:37:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/notte-bianca-dei-libri-in-attesa-della-caccia-al-rifiuto-di-domani\/"},"modified":"2023-01-17T12:58:05","modified_gmt":"2023-01-17T11:58:05","slug":"15602-notte-bianca-dei-libri-in-attesa-della-caccia-al-rifiuto-di-domani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15602-notte-bianca-dei-libri-in-attesa-della-caccia-al-rifiuto-di-domani\/","title":{"rendered":"Notte Bianca dei Libri in attesa della Caccia al Rifiuto di domani"},"content":{"rendered":"<p>CORIGLIANO CALABRO (CS) \u2013&nbsp; Sensibilizzare alla raccolta differenziata e rivitalizzare Piana Caruso.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00c8, questo, l\u2019obiettivo della prima \u201cCaccia al Rifiuto\u201d prevista per domani Sabato 23 Agosto presso la Villa Comunale. La Caccia al Rifiuto \u00e8 stata organizzata dall\u2019Amministrazione Comunale in programma con le associazioni \u201cCitt\u00e0 virtuosa&#8221; e \u201cMagica Festa\u201d. La Caccia al rifiuto, partir\u00e0 domani alle 9 con le iscrizioni dei bambini. Poi si apriranno le ricerche. Prima del pranzo verr\u00e0 effettuata la premiazione. A seguire, alle 18, giochi per bambini e baby dance. L\u2019assessore all\u2019ambiente Chiurco ringrazia, infine, la Ecoross Srl societ\u00e0 aggiudicataria del servizio di raccolta rifiuti, per aver creduto e sostenuto l\u2019iniziativa sociale e ambientale. Oggi invece dalle 21 si svolger\u00e0 &#8220;La Notte Bianca dei Libri&#8221; presso lido Beach Club Barracuda in compagnia di Daniela Valente, scrittrice-editor CoccoleBooks.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO CALABRO (CS) \u2013&nbsp; Sensibilizzare alla raccolta differenziata e rivitalizzare Piana Caruso.<\/p>\n","protected":false},"author":22,"featured_media":35719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-35718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35718"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35719"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}