{"id":35724,"date":"2014-08-22T07:11:37","date_gmt":"2014-08-22T05:11:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/e-state-nei-quartieri-da-caricchio-a-via-degli-stadi-programma\/"},"modified":"2023-01-17T12:58:05","modified_gmt":"2023-01-17T11:58:05","slug":"15605-e-state-nei-quartieri-da-caricchio-a-via-degli-stadi-programma","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15605-e-state-nei-quartieri-da-caricchio-a-via-degli-stadi-programma\/","title":{"rendered":"E&#8230;state nei quartieri, da Caricchio a via degli Stadi (PROGRAMMA)"},"content":{"rendered":"<p>COSENZA &#8211; Musica e divertimento tra le palazzine dei quartieri della citt\u00e0 dei bruzi.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L\u2019Estate nei quartieri, organizzata dall\u2019Amministrazione comunale, riparte, dopo una breve pausa, da Borgo Partenope dove nella serata di domani, Sabato 23 Agosto, a partire dalle 21, la piazza principale della bella frazione a sud di Cosenza, sar\u00e0 animata dall\u2019Associazione culturale Cosenza Autentica in collaborazione con il gruppo Just Us. <strong>\u201cLa musica, ieri e oggi\u201d \u00e8 il tema della serata che, dalle origini folcloristiche calabresi e partenopee si muove verso la musica italiana \u2018sempreverde\u2019<\/strong>, concedendosi anche qualche breve incursione nella musica internazionale della prima met\u00e0 del 1900. <strong>Un repertorio accessibile al largo pubblico, incentrato sul \u201crevival\u201d e sulle sonorit\u00e0 tipiche degli anni \u201960 e \u201970, senza tuttavia trascurare le impronte jazz, pop e blues che sono caratteristiche del gruppo Just Us.<\/strong> La serata sar\u00e0 impreziosita dalle coreografie di Francesca Muoio, giovane allieva di danza, la quale collabora a molti progetti di Cosenza Autentica.<\/p>\n<p>&nbsp;<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Musica e divertimento tra le palazzine dei quartieri della citt\u00e0 dei bruzi.<\/p>\n","protected":false},"author":22,"featured_media":35725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-35724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35724"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35725"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}