{"id":35776,"date":"2014-08-24T03:25:53","date_gmt":"2014-08-24T01:25:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/cgia-mestre-cala-il-credito-delle-banche-aumenta-il-rischio-usura-al-sud\/"},"modified":"2023-01-17T12:58:16","modified_gmt":"2023-01-17T11:58:16","slug":"15632-cgia-mestre-cala-il-credito-delle-banche-aumenta-il-rischio-usura-al-sud","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15632-cgia-mestre-cala-il-credito-delle-banche-aumenta-il-rischio-usura-al-sud\/","title":{"rendered":"Cgia Mestre: cala il credito delle banche, aumenta il rischio usura al Sud"},"content":{"rendered":"<p>VENEZIA &#8211; La fotografia \u00e8 stata scattata dalla Cgia di Mestre, che evidenzia un particolare allarme al Sud.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Negli ultimi due anni infatti, le banche hanno erogato a famiglie e imprese quasi 100 miliardi di euro in meno. Con meno soldi a disposizione e la disoccupazione in aumento, il rischio usura assume dimensioni sempre pi\u00f9 preoccupanti al Sud: soprattutto in Campania, <strong>Calabria<\/strong> e Abruzzo. La Cgia di Mestre rileva come tra la fine del 2011 e del 2013 la diminuzione degli impieghi bancari per le famiglie \u00e8 stata di 9,6 mld (-1,9%), mentre le imprese hanno registrato una flessione di 87,6 mld (-8,8%).<\/p>\n<p>&nbsp;<\/p>\n<p>Per il segretario della Cgia, Giuseppe Bortolussi &#8220;oltre agli effetti della crisi economica e al calo della domanda di credito questa forte riduzione dell&#8217;erogato \u00e8 stata dovuta anche al deciso aumento delle sofferenze bancarie che a giugno di quest&#8217;anno ha toccato la cifra record di 168 miliardi di euro&#8221;. &#8220;Con le sole denunce effettuate all&#8217;Autorit\u00e0 giudiziaria &#8211; conclude Bortolussi &#8211; non \u00e8 possibile dimensionare il fenomeno dell&#8217;usura: le segnalazioni, purtroppo, sono ancora molto poche&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Per la Cgia nelle <strong>aree<\/strong> dove c&#8217;\u00e8 <strong>pi\u00f9 disoccupazione, alti tassi di interesse, maggiore sofferenze, pochi sportelli bancari e tanti protesti,<\/strong> la <strong>situazione<\/strong> \u00e8 decisamente a <strong>rischio<\/strong>. Ebbene, rispetto ad un indicatore nazionale medio pari a 100 &#8211; per la Cgia -, la situazione pi\u00f9 critica si presenta in Campania: l&#8217;indice del rischio usura \u00e8 pari a 164,3 (pari al 64,3% in pi\u00f9 della media Italia), in <strong>Calabria<\/strong> a 146,6 (46,6% in pi\u00f9 rispetto alla media nazionale), in Abruzzo si ferma a 144,6 (44,6% in pi\u00f9 della media Italia). Seguono la Puglia a 139,4 (39,4% in pi\u00f9 della media nazionale) e la Sicilia il livello raggiunge quota 136,2 (36,2% in pi\u00f9 della media Italia). Mentre la realt\u00e0 meno &#8220;esposta&#8221; a questo fenomeno \u00e8 il Trentino Alto Adige, con un indice del rischio usura pari a 51,8 (48,2 punti in meno della media nazionale). Anche la situazione delle altre 2 regioni del Nordest \u00e8 abbastanza rassicurante: il Friuli Venezia Giulia, con 72,2 punti, e il Veneto, con 73,1 punti, si piazzano rispettivamente al penultimo e terzultimo posto della graduatoria nazionale del rischio usura.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VENEZIA &#8211; La fotografia \u00e8 stata scattata dalla Cgia di Mestre, che evidenzia un particolare allarme al Sud.<\/p>\n","protected":false},"author":22,"featured_media":35777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-35776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35776"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35777"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}