{"id":35816,"date":"2014-08-25T07:24:47","date_gmt":"2014-08-25T05:24:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/mare-nostrum-in-arrivo-a-crotone-altri-1375-migranti\/"},"modified":"2023-01-17T12:58:25","modified_gmt":"2023-01-17T11:58:25","slug":"15653-mare-nostrum-in-arrivo-a-crotone-altri-1375-migranti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15653-mare-nostrum-in-arrivo-a-crotone-altri-1375-migranti\/","title":{"rendered":"Mare Nostrum, in arrivo a Crotone altri 1375 migranti"},"content":{"rendered":"<p>CROTONE &#8211; Non si arrestano gli sbarchi di immigrati in Calabria.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Dopo l&#8217;arrivo di un migliaio di persone ieri, a Reggio Calabria, oggi a Crotone, \u00e8 stata convocata una riunione operativa in prefettura, per il coordinamento delle attivit\u00e0 di primo soccorso e assistenza, in occasione del preannunciato arrivo di 1375 migranti, di varie nazionalit\u00e0, a bordo della nave militare S. Giusto, nell&#8217;ambito delle operazioni del dispositivo Mare Nostrum. L&#8217;arrivo della nave nel Porto di Crotone \u00e8 previsto presumibilmente per le ore 15 di oggi. All&#8217;incontro hanno partecipato il sindaco di Crotone, il comandante della Capitaneria di Porto, i rappresentanti delle forze di polizia, dei vigili del fuoco, del Suem 118, della Protezione Civile regionale, dell&#8217;Azienda sanitaria provinciale, delle associazioni di volontariato, della Croce Rossa e della Misericordia. Nel corso della seduta sono stati definiti gli aspetti organizzativi e logistici delle operazioni attinenti allo sbarco e la puntuale individuazione degli adempimenti facenti capo ai soggetti istituzionalmente coinvolti nel citato dispositivo. La Prefettura ha disposto l&#8217;istituzione di una sala operativa presso la competente Capitaneria di Porto per assicurare una piu&#8217; efficace ed efficiente direzione dei soccorsi ed ha programmato le necessarie attivita&#8217; di prima assistenza in favore dei migranti. Un centinaio circa di migranti sara&#8217; ospitato presso il locale CDA\/CARA di Isola di Capo Rizzuto in attesa della compiuta definizione da parte del Ministero dell&#8217;Interno del piano di riparto con destinazione in diverse Regioni del Paese, presso le quali i migranti verranno trasferiti dopo le operazioni di sbarco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Non si arrestano gli sbarchi di immigrati in Calabria.<\/p>\n","protected":false},"author":19,"featured_media":35817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-35816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35816"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35817"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}