{"id":35876,"date":"2014-08-27T07:07:04","date_gmt":"2014-08-27T05:07:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/rilievi-arpacal-c-e-da-fidarsi-almeno-sulla-carta\/"},"modified":"2023-01-17T12:58:30","modified_gmt":"2023-01-17T11:58:30","slug":"15683-rilievi-arpacal-c-e-da-fidarsi-almeno-sulla-carta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15683-rilievi-arpacal-c-e-da-fidarsi-almeno-sulla-carta\/","title":{"rendered":"Rilievi Arpacal: c&#8217;\u00e8 da fidarsi, almeno &#8216;sulla carta&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"center\">ROMA &#8211; All&#8217;Arpacal va il merito di essere l&#8217;unico sito, tra le agenzie ambientali italiane, totalmente trasparente.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Bussola della trasparenza: la funzione pubblica promuove a pieni voti la Calabria. Secondo i controlli in tempo reale sulla trasparenza dei siti web istituzionali degli enti pubblici italiani, a cura del Dipartimento Funzione Pubblica e consultabili all\u2019indirizzo <a href=\"http:\/\/www.magellanopa.it\/bussola\" rel=\"noopener\">www.magellanopa.it\/bussola<\/a> , il sito web dell\u2019Agenzia regionale per la protezione dell\u2019ambiente della Calabria (Arpacal), consultabile all\u2019indirizzo <a href=\"http:\/\/www.arpacal.it\" rel=\"noopener\">www.arpacal.it<\/a> , primeggia in materia di trasparenza. E\u2019 quanto comunica il Dott. Vincenzo Iuli, dirigente Responsabile della Prevenzione della Corruzione e per la Trasparenza per l\u2019Arpacal, che da gennaio scorso sta seguendo personalmente gli adempimenti dell\u2019Ente connessi alla normativa sulla trasparenza.<\/p>\n<p>&nbsp;<\/p>\n<p>La \u201cBussola della Trasparenza\u201d \u00e8 l\u2019iniziativa del Dipartimento della Funzione Pubblica che consente alle pubbliche amministrazioni e ai cittadini di utilizzare strumenti per l\u2019analisi ed il monitoraggio dei siti web degli enti pubblici italiani, rafforzando, in linea con i principi dell\u2019Open Government, la partecipazione, la trasparenza e l\u2019accountability, ossia la verificabilit\u00e0 delle attivit\u00e0 svolte dall\u2019ente. Il plauso per questo importante e qualificato obiettivo \u00e8 giunto dal direttore generale dell\u2019Arpacal, dr.ssa Sabrina Santagati, che ha sottolineato come \u201csia prioritario, soprattutto per un\u2019agenzia che lavora sul territorio come l\u2019Arpacal, garantire massima trasparenza nei propri atti, rendendoli conoscibili e consultabili dagli stessi cittadini che, in quanto utenti, usufruiscono dei servizi che, quotidianamente, svolgiamo nelle diverse matrici ambientali\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; All&#8217;Arpacal va il merito di essere l&#8217;unico sito, tra le agenzie ambientali italiane, totalmente trasparente.<\/p>\n","protected":false},"author":22,"featured_media":35877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-35876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35876"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35877"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}