{"id":3593,"date":"2012-09-13T05:40:13","date_gmt":"2012-09-13T03:40:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3593"},"modified":"2023-01-17T13:36:20","modified_gmt":"2023-01-17T12:36:20","slug":"669-cosenza-inaugurazione-del-parco-storico-giuseppina-le-maire","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/669-cosenza-inaugurazione-del-parco-storico-giuseppina-le-maire\/","title":{"rendered":"Cosenza: inaugurazione del parco storico Giuseppina Le Maire"},"content":{"rendered":"<p><span style=\"font-size: 12px; line-height: 18.649999618530273px; background-color: #ffffff;\">COSENZA &#8211; Si svolger\u00e0 venerd\u00ec 14 settembre presso la sala Quintieri del Teatro A. Rendano di Cosenza la cerimonia di inaugurazione del parco storico \u201cGiuseppina Le Maire\u201d, promosso dalla fondazione Fidapa di cui \u00e8 referente in Calabria la dott.ssa Tania Frisone Severino.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Si svolger\u00e0 venerd\u00ec 14 settembre presso la sala Quintieri del Teatro A. Rendano di Cosenza la cerimonia di inaugurazione del parco storico \u201cGiuseppina Le Maire\u201d, promosso dalla fondazione Fidapa di cui \u00e8 referente in Calabria la dott.ssa Tania Frisone Severino.<\/p>\n","protected":false},"author":22,"featured_media":1110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-3593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3593"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/1110"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}