{"id":35980,"date":"2014-08-29T10:46:36","date_gmt":"2014-08-29T08:46:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/primarie-calabria-ad-andare-al-voto-e-solo-un-partito\/"},"modified":"2023-01-17T12:58:36","modified_gmt":"2023-01-17T11:58:36","slug":"15735-primarie-calabria-ad-andare-al-voto-e-solo-un-partito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15735-primarie-calabria-ad-andare-al-voto-e-solo-un-partito\/","title":{"rendered":"Primarie Calabria ad andare al voto \u00e8 solo un partito"},"content":{"rendered":"<p>CATANZARO &#8211; C&#8217;\u00e8 solo una lista candidata alle prossime primarie per le elezioni Regionali Calabria.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Indette per il 21 Settembre l&#8217;unica candidatura presentata \u00e8 quella di Diritti Civili. Oggi alla chiusura delle presentazioni a mezzogiorno la candidatura del leader di Diritti civili, Franco Corbelli, dell&#8217;ex sottosegretario Elio Belcastro e di Antonietta Perri, erano le uniche ufficializzate negli uffici della Regione Calabria preposte al vaglio dei requisiti. Poco prima delle 12 era spuntata fuori anche la candidatura dell&#8217;Associazione &#8220;Amici della Calabria&#8221;, di cui \u00e8 rappresentante il consigliere regionale del Pd, Mario Maiolo. Un collaboratore dell&#8217;esponente politico, aveva presentato la documentazione per il gruppo Amici della Calabria. Nel giro di pochi minuti, per\u00f2, la candidatura \u00e8 sfumata.<\/p>\n<p>&nbsp;<\/p>\n<p>Lo stesso Maiolo ha infatti comunicato ai funzionari addetti la decisione di ritirarsi dalla competizione. Davanti alla sede della Regione Calabria dove sono ubicati gli uffici preposti all&#8217;accettazione della documentazione per le primarie per legge, sempre in mattinata, si erano presentati anche i collaboratori del presidente della Provincia di Cosenza Mario Oliverio con le firme. I rappresentanti di Oliverio hanno desistito dopo che da Roma \u00e8 arrivato il documento del vicesegretario Debora Serracchiani sottoscritto dallo stesso Oliverio e dall&#8217;altro candidato del Pd Gianluca Callipo in cui c&#8217;\u00e8 l&#8217;assicurazione della fissazione di primarie di coalizione a breve termine.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Non siamo da soli, dietro di noi c&#8217;\u00e8 la Calabria, ci sono i calabresi e a chi pone il problema dei costi per le primarie diciamo che, forse per la prima volta in questa regione, si tratter\u00e0 di soldi spesi bene. E lo dice chi ha sempre devoluto in beneficenza le proprie indennit\u00e0&#8221;. Lo ha detto Franco Corbelli, a margine del deposito stamani. &#8220;Noi vogliamo &#8211; ha aggiunto Corbelli &#8211; che la Calabria diventi protagonista e reagisca. I calabresi non possono accettare passivamente che il loro futuro venga determinato nelle stanze degli inciuci romani. Per quanto ci riguarda vogliamo che siano i calabresi attraverso le primarie a pronunciarsi. Questo \u00e8 il senso della nostra iniziativa che andr\u00e0 avanti per la sua strada. Non ci condiziona il fatto che siamo da soli. Oggi \u00e8 un giorno importante per la democrazia e per la Calabria. Diritti civili dar\u00e0 la possibilit\u00e0 a tutti i calabresi di decidere il loro futuro e il loro candidato presidente. La competizione andr\u00e0 al di l\u00e0 della nostra lista e della mia candidatura, di quella del sottosegretario Elio Belcastro e della giovane laureata Antonietta Perri&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; C&#8217;\u00e8 solo una lista candidata alle prossime primarie per le elezioni Regionali Calabria.<\/p>\n","protected":false},"author":22,"featured_media":35981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-35980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=35980"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/35980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/35981"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=35980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=35980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=35980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}