{"id":3607,"date":"2012-09-13T06:50:40","date_gmt":"2012-09-13T04:50:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3607"},"modified":"2023-01-17T13:36:22","modified_gmt":"2023-01-17T12:36:22","slug":"683-iphone-5-in-italia-dal-28-settembre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/683-iphone-5-in-italia-dal-28-settembre\/","title":{"rendered":"iPhone 5, in Italia dal 28 settembre"},"content":{"rendered":"<p style=\"text-align: justify;\">Davanti alla platea dello <a href=\"http:\/\/www.zeusnews.it\/util\/extlink\/cerca.php?q=Yerba%20Buena%20Center\" target=\"_blank\" title=\"Yerba Buena Center\" rel=\"noopener\">Yerba Buena Center<\/a> di San Francisco, <a href=\"http:\/\/www.zeusnews.it\/util\/extlink\/cerca.php?q=Tim%20Cook\" target=\"_blank\" title=\"Tim Cook\" rel=\"noopener\">Tim Cook<\/a> e <a href=\"http:\/\/www.zeusnews.it\/util\/extlink\/cerca.php?q=Phil%20Schiller\" target=\"_blank\" title=\"Phil Schiller\" rel=\"noopener\">Phil Schiller<\/a> si sono<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">avvicendati per mostrare le novit\u00e0 di Apple dominate, naturalmente, dall&#8217;<a href=\"http:\/\/www.zeusnews.it\/link\/17358\" target=\"_blank\" title=\"http:\/\/www.apple.com\/it\/iphone\/\" rel=\"noopener\">iPhone 5<\/a>.<\/p>\n<p style=\"text-align: justify;\">L&#8217;ultimo modello del dispositivo che ha creato il settore degli smartphone come lo conosciamo oggi ha mantenuto il numero a fianco del proprio nome e in buona parte ha confermato <a href=\"http:\/\/www.zeusnews.it\/zn\/18244\" target=\"_blank\" title=\"Ecco che cosa vedremo nell&#039;iPhone 5\" rel=\"noopener\">le attese e le indiscrezioni<\/a>.<\/p>\n<div style=\"text-align: justify;\"><ins><ins id=\"aswift_2_anchor\"><\/ins><\/ins> <\/p>\n<div id=\"beacon_5f917f500a\"><\/div>\n<div>&nbsp;<\/div>\n<\/p><\/div>\n<p style=\"text-align: justify;\">Innanzitutto \u00e8 cresciuto nello schermo, che ora misura 4 pollici in diagonale ed \u00e8 diventato pi\u00f9 lungo ma ha mantenuto la stessa larghezza e la stessa densit\u00e0 di <a href=\"http:\/\/www.zeusnews.it\/index.php3?ar=stampa&amp;cod=18249&amp;boxone=1\" id=\"itxthook0\" rel=\"nofollow noopener\"><span id=\"itxthook0w0\">pixel<\/span><\/a> (326 dpi); la risoluzione ora \u00e8 pari a 1136&#215;640 pixel.<\/p>\n<p style=\"text-align: justify;\">L&#8217;<a href=\"http:\/\/www.zeusnews.it\/index.php3?ar=stampa&amp;cod=18249&amp;boxone=1\" id=\"itxthook1\" rel=\"nofollow noopener\"><span id=\"itxthook1w0\">iPhone<\/span><\/a> 5 \u00e8 anche frutto di una decisa cura dimagrante e ora si presenta come \u00ablo smartphone pi\u00f9 sottile al mondo\u00bb grazie ai propri 7,6 millimetri di spessore; grazie all&#8217;uso del vetro e dell&#8217;alluminio \u00e8 anche pi\u00f9 leggero di prima e pesa 112 grammi, ossia il 20% in meno dell&#8217;iPhone 4S.<\/p>\n<p style=\"text-align: justify;\">Sempre per quanto riguarda i materiali, come gi\u00e0 era stato anticipato ora il retro \u00e8 costituito in buona parte in alluminio &#8211; il che lo rende pi\u00f9 robusto &#8211; mentre, sempre rispettando le indiscrezioni, ora lo strato dei sensori \u00e8 fuso nel pannello <a href=\"http:\/\/www.zeusnews.it\/index.php3?ar=stampa&amp;cod=18249&amp;boxone=1\" id=\"itxthook2\" rel=\"nofollow noopener\"><span id=\"itxthook2w0\">LCD<\/span><\/a>, e anche questo ha contribuito a ridurre lo spessore.<\/p>\n<p style=\"text-align: justify;\">A parte tutto ci\u00f2, le differenze estetiche con il modello precedente sono ridotte: non c&#8217;\u00e8 stata una rivoluzione nel design come qualcuno si aspettava, e per questo motivo c&#8217;\u00e8 chi parla di delusione.<\/p>\n<p style=\"text-align: justify;\">All&#8217;interno dello smartphone Apple ha inserito il <a href=\"http:\/\/www.zeusnews.it\/index.php3?ar=stampa&amp;cod=18249&amp;boxone=1\" id=\"itxthook3\" rel=\"nofollow noopener\"><span id=\"itxthook3w0\">processore<\/span><\/a> A6, pubblicizzato come \u00abdue volte pi\u00f9 veloce dell&#8217;A5\u00bb.<\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda la connettivit\u00e0, \u00e8 stato inserito il supporto alle <a href=\"http:\/\/www.zeusnews.it\/index.php3?ar=stampa&amp;cod=18249&amp;boxone=1\" id=\"itxthook4\" rel=\"nofollow noopener\"><span id=\"itxthook4w0\">reti<\/span><\/a> 4G LTE a 2100, 1800 e 850 MHz, ampliando cos\u00ec la compatibilit\u00e0 con le frequenze utilizzate al di fuori degli Stati Uniti; per quanto riguarda l&#8217;Italia &#8211; dove comunque ancora non c&#8217;\u00e8 un&#8217;offerta commerciale per LTE &#8211; questa scelta non \u00e8 ancora ideale, dato che le frequenze da noi assegnate a LTE sono 2600, 1800 e 800 MHz.<\/p>\n<p style=\"text-align: justify;\">Anche il Wi-Fi ha fatto passi in avanti, acquisendo il supporto alle reti che sfruttano lo standard 802.11n sia a 2,4 che a 5 GHz.<\/p>\n<p style=\"text-align: justify;\">Per l&#8217;iPhone 5 Apple ha deciso di puntare molto sulle fotocamere, portando l&#8217;alta definizione anche su quella anteriore (che dunque ora permette di utilizzare FaceTime in HD); quella posteriore ha mantenuto il sensore da 8 <a href=\"http:\/\/www.zeusnews.it\/index.php3?ar=stampa&amp;cod=18249&amp;boxone=1\" id=\"itxthook5\" rel=\"nofollow noopener\"><span id=\"itxthook5w0\">megapixel<\/span><\/a> ma \u00e8 stata migliorata e ora le foto sono pi\u00f9 nitide e i colori pi\u00f9 fedeli. Debutta inoltre la funzione panorama che consente di realizzare, per l&#8217;appunto, foto panoramiche.<\/p>\n<div style=\"text-align: justify;\"> (Fai clic sull&#8217;immagine per visualizzarla ingrandita)<\/div>\n<p style=\"text-align: justify;\">Le due novit\u00e0 che rompono completamente col passato riguardano ancora l&#8217;hardware: si tratta del nuovo connettore dock (battezzato Lightning), ora di dimensioni comparabili a quelle di una porta miniUSB, e dell&#8217;adozione delle <a href=\"http:\/\/www.zeusnews.it\/zn\/17667\" target=\"_blank\" title=\"Approvate le nuove nanoSIM, Apple ringrazia\" rel=\"noopener\">nanoSIM<\/a> al posto delle gi\u00e0 minuscole miniSIM.<\/p>\n<p style=\"text-align: justify;\">L&#8217;apparizione di un nuovo connettore ha costretto Apple a presentare anche i necessari adattatori per consentire agli utenti di adoperare i vecchi accessori, tuttavia la completa compatibilit\u00e0 non pu\u00f2 essere garantita.<\/p>\n<p style=\"text-align: justify;\">Utilizzare un iPhone non significa per\u00f2 soltanto acquistare un dispositivo hardware, ma anche avere a che fare con un software appositamente realizzato: nel caso dell&#8217;iPhone 5 ci\u00f2 significa parlare di iOS 6.<\/p>\n<p style=\"text-align: justify;\">L&#8217;ultima versione del <a href=\"http:\/\/www.zeusnews.it\/index.php3?ar=stampa&amp;cod=18249&amp;boxone=1\" id=\"itxthook6\" rel=\"nofollow noopener\"><span id=\"itxthook6w0\">sistema<\/span><span id=\"itxthook6w1\"> <\/span><span id=\"itxthook6w2\">operativo<\/span><\/a>, che debutta ufficialmente il 19 settembre, vede sparire definitivamente le applicazioni di Google: YouTube non \u00e8 pi\u00f9 installato di default, e per le mappe &#8211; <a href=\"http:\/\/www.zeusnews.it\/zn\/17700\" target=\"_blank\" title=\"Apple rinuncia a Google Maps su iOS\" rel=\"noopener\">come ci si aspettava<\/a> &#8211; ora Apple si serve di quelle realizzate da 3D Technologies, acquisita qualche tempo fa.<\/p>\n<p style=\"text-align: justify;\">Per effettuare le ricerche la scelta principe resta naturalmente Siri, l&#8217;assistente vocale, che ora parla anche italiano, mentre il portafogli <a href=\"http:\/\/www.zeusnews.it\/index.php3?ar=stampa&amp;cod=18249&amp;boxone=1\" id=\"itxthook7\" rel=\"nofollow noopener\"><span id=\"itxthook7w0\">digitale<\/span><\/a> viene gestito da PassBook.<\/p>\n<div style=\"text-align: justify;\"> (Fai clic sull&#8217;immagine per visualizzarla ingrandita)<\/div>\n<p style=\"text-align: justify;\">La presenza dell&#8217;integrazione con Facebook e Twitter, per quanto gradita agli utenti dei social netwok, non sorprender\u00e0 nessuno, mentre per quanto riguarda la condivisione di foto Apple ha inserito l&#8217;applicazione apposita Photo Stream.<\/p>\n<p style=\"text-align: justify;\">Una menzione merita anche la riprogettazione degli auricolari: quelli finora forniti in dotazione non sono mai piaciuti a nessuno, mentre i nuovi EarPods con <a href=\"http:\/\/www.zeusnews.it\/index.php3?ar=stampa&amp;cod=18249&amp;boxone=1\" id=\"itxthook8\" rel=\"nofollow noopener\"><span id=\"itxthook8w0\">telecomando<\/span><\/a> e microfono promettono di restituire suoni pieni e fedeli.<\/p>\n<p style=\"text-align: justify;\">Apple ha confermato anche la data di lancio americana: l&#8217;iPhone 5 &#8211; in versione nera o bianca &#8211; sar\u00e0 in vendita negli USA a partire dal 21 settembre con prezzi che, sottoscrivendo un contratto, saranno di 199 dollari (versione da 16 Gbyte), 299 dollari (32 Gbyte) e 299 dollari (64 Gbyte).<\/p>\n<p style=\"text-align: justify;\">Il lancio in Italia avverr\u00e0 prima di quanto si supponesse: l&#8217;iPhone arriver\u00e0 nel nostro Paese il 28 settembre, appena una settimana dopo il lancio negli USA. A breve Apple comunicher\u00e0 i prezzi del telefono sbloccato e gli operatori presenteranno le proprie offerte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Davanti alla platea dello Yerba Buena Center di San Francisco, Tim Cook e Phil Schiller si sono<\/p>\n","protected":false},"author":22,"featured_media":1138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34,5,61],"tags":[],"class_list":["post-3607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine","category-old","category-tecnologia-e-internet"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3607"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/1138"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}