{"id":36176,"date":"2014-09-05T08:14:28","date_gmt":"2014-09-05T06:14:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/corigliano-aderisce-al-concorso-fotografico-wikipedia-2-800-euro-in-palio\/"},"modified":"2023-01-17T12:58:50","modified_gmt":"2023-01-17T11:58:50","slug":"15838-corigliano-aderisce-al-concorso-fotografico-wikipedia-2-800-euro-in-palio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15838-corigliano-aderisce-al-concorso-fotografico-wikipedia-2-800-euro-in-palio\/","title":{"rendered":"Corigliano aderisce al concorso fotografico Wikipedia, 2.800 euro in palio"},"content":{"rendered":"<p>CORIGLIANO CALABRO (CS) \u2013 Wiki Loves Monuments Italia, Corigliano c&#8217;\u00e8.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Raccontare il territorio ed il patrimonio monumentale attraverso l\u2019obiettivo fotografico. Il termine ultimo per partecipare al concorso fotografico nazionale \u00e8 il 30 settembre. Si concorre per un montepremi di 2mila e 800 euro; le foto vincitrici saranno utilizzate per illustrare gli articoli di Wikipedia in tutte le lingue. Si tratta del concorso fotografico promosso da Wikipedia per valorizzare il patrimonio culturale italiano, potenziando la visibilit\u00e0 dei monumenti e delle emergenze architettoniche e artistiche del Bel Paese e rendendo ciascuno protagonista di questo lavoro di documentazione e valorizzazione. Qualit\u00e0 tecnica, originalit\u00e0 e utilit\u00e0 per Wikipedia. Sono, questi, i criteri per la selezione delle opere finaliste.<strong> Il Castello Ducale, il Cinema Teatro Valente, il Complesso della Riforma, il Convento delle Clarisse ex Pretura, il Palazzo Caruso \u2013 Bianchi ed il Palazzo dell&#8217;Orologio, nel borgo antico, ed il Palazzo delle Fiere o Quadrato Campagna a Schiavonea. Sono, questi, i monumenti scelti e di cui, attraverso l\u2019adesione al progetto, l\u2019Esecutivo Geraci, autorizza la pubblicazione su Wikimedia Commons.<\/strong> La licenza che deve essere riportata \u00e8 CC-BY-SA-it 3.0. Per partecipare basta, quindi, registrarsi e caricare una fotografia di uno dei monumenti elencati sul sito <a href=\"http:\/\/www.wikilovesmonuments.it\" rel=\"noopener\">www.wikilovesmonuments.it<\/a> entro il 30 settembre. La premiazione avverr\u00e0 nel mese di Novembre 2014.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO CALABRO (CS) \u2013 Wiki Loves Monuments Italia, Corigliano c&#8217;\u00e8.<\/p>\n","protected":false},"author":22,"featured_media":36177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-36176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=36176"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/36177"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=36176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=36176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=36176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}