{"id":36212,"date":"2014-09-06T08:48:07","date_gmt":"2014-09-06T06:48:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/i-debiti-si-scaricano-sui-cittadini-niente-scuolabus-e-tasse-alle-stelle\/"},"modified":"2023-01-17T12:58:52","modified_gmt":"2023-01-17T11:58:52","slug":"15856-i-debiti-si-scaricano-sui-cittadini-niente-scuolabus-e-tasse-alle-stelle","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15856-i-debiti-si-scaricano-sui-cittadini-niente-scuolabus-e-tasse-alle-stelle\/","title":{"rendered":"I debiti si scaricano sui cittadini, niente scuolabus e tasse alle stelle"},"content":{"rendered":"<p style=\"text-align: justify;\">MONTALTO UFFUGO &#8211; Gli strascichi dell&#8217;amministrazione decennale di Ugo Gravina pesano come un macigno sulle casse comunali di Montalto Uffugo.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Una situazione ormai fuori controllo quella dei bilanci del Comune che rischiano di finire sui banchi della procura generale della Corte dei Conti. Solo la sua pronuncia potr\u00e0 individuare i responsabili del crollo delle finanze montaltesi. A ribadire la gravit\u00e0 dello stato attuale in cui verte il municipio sono gli attivisti del Movimento Cinque Stelle di Montalto. &#8220;Il Comune \u00e8 pieno di debiti &#8211; affermano in una nota&nbsp; &#8211; e si rischia il dissesto, per come annunciato anche dall\u2019assessore al bilancio. La drammatica situazione delle casse comunali non \u00e8 cosa di oggi, ma <strong>gi\u00e0 da tempo si sapeva che la precedente amministrazione durante i suoi anni di gestione aveva effettuato una gestione a dir poco allegra e che il sindaco subentrante non avrebbe avuta vita facile.<\/strong> Tutto questo ha costretto l\u2019attuale amministrazione ad aumentare le aliquote della TASI e ad effettuare dei tagli sulla spesa con la speranza di poter salvare dal dissesto le casse comunali.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Noi speriamo che l\u2019amministrazione riesca nel suo intento, per\u00f2 nel frattempo i cittadini montaltesi <strong>dovranno rinunciare a tante cose e non solo al Festival del Leoncavallo ma a tanti altri servizi necessari che, cosi almeno sembra, non saranno attivati dall\u2019ente, tra i quali il servizio scuolabus<\/strong>. Siamo anche convinti che l\u2019aumento della tassazione non porter\u00e0 maggiori introiti nelle casse comunali, vista l\u2019attuale situazione economica nazionale che nel nostro territorio \u00e8 maggiormente acutizzata visto che in questi ultimi periodi molte aziende hanno chiuso i battenti lasciando a casa molti nostri cittadini. Per quanto ci riguarda chiediamo che l\u2019Amministrazione, vista la situazione contabile riscontrata nell\u2019ente, proceda ad inoltrare alla Procura Generale della Corte di Conti regionale una dettagliata informativa affinch\u00e9 i giudici contabili possano valutare se vi sono responsabilit\u00e0 da parte dei precedenti amministratori o responsabili degli uffici comunali in questa poca attenta gestione dell\u2019ente locale. Qualora il nostro invito non venisse recepito provvederemo autonomamente ad inoltrare una denuncia alla Corte dei Conti chiedendo di voler avviare le eventuali verifiche contabili&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTALTO UFFUGO &#8211; Gli strascichi dell&#8217;amministrazione decennale di Ugo Gravina pesano come un macigno sulle casse comunali di Montalto Uffugo.<\/p>\n","protected":false},"author":22,"featured_media":36213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,565],"tags":[],"class_list":["post-36212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-castrolibero-montalto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=36212"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/36213"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=36212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=36212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=36212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}