{"id":36265,"date":"2014-09-08T13:04:50","date_gmt":"2014-09-08T11:04:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/riparte-invasioni-2014-il-programma-completo\/"},"modified":"2023-01-17T12:59:00","modified_gmt":"2023-01-17T11:59:00","slug":"15883-riparte-invasioni-2014-il-programma-completo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15883-riparte-invasioni-2014-il-programma-completo\/","title":{"rendered":"Riparte Invasioni 2014, ecco il programma completo"},"content":{"rendered":"<p>COSENZA &#8211; Dal 10 al 20 Settembre si terr\u00e0 a Cosenza il Festival delle Invasioni.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L&#8217;edizione 2014 della tradizionale kermesse bruzia invita i cittadini a lasciare che l\u2019arte invada le proprie menti. E&#8217; su questo leitmotiv che gli organizzatori hanno studiato il calendario degli eventi che animeranno Cosenza per dieci giorni consecutivi approfittando degli ultimi scorci d&#8217;estate. Proponiamo di seguito l&#8217;interessante programma della manifestazione che prender\u00e0 il via a partire dalla giornata di Mercoled\u00ec sul tema &#8216;L\u2019Arte invade la Mente&#8217;. La location sar\u00e0 quella del centro storico in cui l\u2019Area Festival sar\u00e0 allestita con delle isole del gusto che proporranno cucina etnica e dj set nel dopo concerti. I luoghi del Festival saranno raggiungibili usufruendo delle navette che l\u2019AMACO, per l&#8217;occasione, metter\u00e0 a disposizione.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mercoled\u00ec 10 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\u2013 ORE 10,00 Inaugurazione delle mostre ARS LONGA VITA LONGA (a cura di Bruno La Vergata) aperte al pubblico&nbsp;da luned\u00ec al sabato dalle 10,00 alle 12,00 e dalle 16,00 alle 18,00 nelle scuole: Scuola elementare Spirito Santo (al suo interno la mostra dei diversamente pensanti&nbsp; di borgo dei mastri&nbsp; e della scuola carceraria); Scuola elementare&nbsp; via Roma; Scuola elementare Don Milani De Matera; Scuola media via Zumbini; Liceo artistico; Liceo classico B. Telesio; Liceo Lucrezia Della Valle ed ITC Pezzullo.<\/p>\n<p>\u2013 ORE 16,00 Chiostro di San Domenico Inaugurazione delle mostre OBSESSION (a cura di Paolo Aita) aperte al pubblico dalle 10.00 alle 12 e dalle 17 alle 20 all&#8217;interno del Cinema Morelli, del Teatro Rendano; del Convitto Nazionale; del Chiostro San Domenico; della Biblioteca Nazionale; della Villa Rendano; del Chiostro Santa Chiara; del Chiostro San Francesco; del Museo dei Bretti e della Casa delle Culture.<\/p>\n<p>\u2013 ORE 19,00 Inaugurazione della mostra di 70 artisti cosentini e non LIBERAMENTE (a cura di Carmelita Brunetti) aperte al pubblico dalle 10.00 alle 12 e dalle 17 alle 22 all&#8217;interno del MAM Museo delle Arti e Mestieri.<\/p>\n<p>&#8211; ORE 21,30 Anfiteatro VIlla Vecchia concerto della cantante africana Angelique Kidjo<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gioved\u00ec 11 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; ORE 18,00 Proiezione del film CONTAINER 158 al Chiostro di Santa Chiara a seguire dibatto sulle politiche di inclusione delle comunit\u00e0 SInti e ROM<\/p>\n<p>&#8211; ORE 22,00&nbsp;Anfiteatro VIlla Vecchia live dei Bamboo gruppo ispirato ai Radiohead che suona <span class=\"st\">drum and bass usando cartelli stradali e frullatori<\/span>&nbsp; &nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Venerd\u00ec 12 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; ORE 18,00 Conversazione con Emanuela Catalano all&#8217;interno del MAM Museo delle Arti e Mestieri. La critica d\u2019arte internazionale parla dell\u2019arte contemporanea e comunica in via immediata le sue impressioni sulle mostre allestite per Invasioni 2014.<\/p>\n<p>&#8211; ORE 23,00 Anfiteatro VIlla Vecchia concerto del cantante irlandese Wallis Bird<br \/>&nbsp;<\/p>\n<p><strong>Sabato 13 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; ORE 10-20 BIMBO IN FABULA rassegna laboratoriale ludica di arte, musica, scienze, natura con spettacoli per i pi\u00f9 piccoli tra truccatori, clown e la mongolfiera UP<\/p>\n<p>&#8211; ORE 21,30 Anfiteatro VIlla Vecchia concerto blues con Elliot Murphy<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Domenica 14 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; ORE 10-20 BIMBO IN FABULA rassegna laboratoriale ludica di arte, musica, scienze, natura con spettacoli per i pi\u00f9 piccoli tra truccatori, clown e la mongolfiera UP&nbsp;<\/p>\n<p>&#8211; ORE 11,00 Visita guidata al MAB, teatro itinerante a cura del Parco Tommaso Campanella, INCANTI DALL&#8217;ISOLA CHE C&#8217;E&#8217;<\/p>\n<p>&#8211; ORE 21,00 Proiezione Film&nbsp;IL CAPITALE UMANO di Paolo Virz\u00ec in piazza XI Settembre<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Marted\u00ec 16 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; ORE 21,00 Proiezione Film ed incontro dibattito al Supercinema Modernissimo IL SOGNO DI MILANO di Mimmo Calopresti, UNO DI NOI, SOCRATES di Mimmo Calopresti<\/p>\n<p>&#8211; ORE 20,00 Proiezione in anteprima mondiale del Film-documentario su GREGORY CORSO per la regia di Matteo Scarf\u00f2 presso il Chiostro di Santa Chiara<\/p>\n<p>&#8211; ORE 21,30 Chiostro di Santa Chiara concerto dei NINBI formazione catanzarese di progressive rock che ha composto la colonna sonora del film su Gregory Corso<\/p>\n<p>&#8211; ORE 18,00 Casa delle Culture l&#8217;economista Pierangelo Dacrema presenta il suo libro \u201cMarx e Keynes \u2013 un Romanzo Economico\u201d insieme a Marco Dotti dell&#8217;Universit\u00e0 di Pavia e Franco Piperno dell&#8217;Universit\u00e0 della Calabria<br \/>&nbsp;<\/p>\n<p><strong>Mercoled\u00ec 17 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; ORE 21,00 Proiezione Film LA MAFIA UCCIDE SOLO D\u2019ESTATE di Pif al CInema Citrigno<\/p>\n<p>&#8211; ORE 22,00 Anfiteatro VIlla Vecchia concerto della band piemontese <span class=\"st\">pop rock Perturbazione<\/span> a seguire dj set Paescuetta Happy Music, revival e funk<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gioved\u00ec 18 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; ORE 21,30 Anfiteatro VIlla Vecchia COMMEDIA scritta per Cosenza di e con Giorgio Barberio Corsetti e Danilo Rea<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Venerd\u00ec 19 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; ORE 20,00 Piazza Duomo OMAGGIO A SAMUEL BECKETT per la regia di Francesca Marchese e Luigi Simone Veneziani<\/p>\n<p>&#8211; ORE 21,30 Anfiteatro VIlla Vecchia concerto della cantante blues calabrese Stefania Calandra a seguire DJ set di Iguana The Cooker<br \/><strong>&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><br \/><strong>Sabato 20 SETTEMBRE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;&#8211; ORE 21,30 Anfiteatro VIlla Vecchia STAZIONI LUNARI spettacolo musicale itinerante al quale prenderanno parte diversi autori e musicisti tra i quali Enzo Avitabile, Ginevra Di Marco, Massimo Zamboni, Fatur e Cristiano Godano<\/p>\n<p>&#8211; ORE 19,00 Villa Rendano FEED-BACK TANZ 0.1 di e con Orazio Garofalo e Francesca Marchese<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>LE ESPOSIZIONI NELLE GALLERIE D\u2019ARTE DI COSENZA<\/li>\n<\/ol>\n<p>&#8211;&nbsp;&nbsp; &nbsp;L\u2019IMPRONTA INSTALLAZIONE PERFORMATIVA A CURA DI MARIA CARLA MAIOLO RITROVARE UN GUANTO dal 19 settembre<br \/>&#8211;&nbsp;&nbsp; &nbsp;IL TRIANGOLO ESPONE ACQUARELLI E DISEGNI DI UN MAESTRO DELL\u2019 \u2018800 ROMANO \u2013 SCIPIONE VENNUTELLI (1834-1894)<br \/>&#8211;&nbsp;&nbsp; &nbsp;MARANO ESPONE IL MAESTRO ANTONIO SCIACCA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Dal 10 al 20 Settembre si terr\u00e0 a Cosenza il Festival delle Invasioni.<\/p>\n","protected":false},"author":22,"featured_media":36266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-36265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=36265"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/36266"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=36265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=36265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=36265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}