{"id":36327,"date":"2014-09-10T08:55:14","date_gmt":"2014-09-10T06:55:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/singolare-incidente-sull-a3-auto-si-schianta-contro-l-autovelox\/"},"modified":"2023-01-17T12:59:06","modified_gmt":"2023-01-17T11:59:06","slug":"15915-singolare-incidente-sull-a3-auto-si-schianta-contro-l-autovelox","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15915-singolare-incidente-sull-a3-auto-si-schianta-contro-l-autovelox\/","title":{"rendered":"Singolare incidente sull&#8217;A3, auto si schianta contro l&#8217;autovelox"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; L&#8217;alta velocit\u00e0 che si scontra con il sistema che&#8230; la controlla.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un singolare incidente stradale si \u00e8 verificato sull&#8217;A3 Salerno Reggio Calabria, al chilometro 347, all&#8217;altezza dello svincolo per Vibo Valentia-Sant&#8217;Onofrio, in direzione sud. Un&#8217;auto, una Fiat Punto di colore blu, sulla quale viaggiavano quattro persone originarie del Reggino, tutte imparentate tra loro, tra cui una bimba appena nata, si \u00e8 schiantata per cause ancora in corso d&#8217;accertamento contro una postazione autovelox che \u00e8 stata sradicata e trascinata per circa 30 metri. Fortunatamente solo tanta paura per gli occupanti dell&#8217;auto ma nessuna conseguenza fisica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; L&#8217;alta velocit\u00e0 che si scontra con il sistema che&#8230; la controlla.<\/p>\n","protected":false},"author":19,"featured_media":36328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-36327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=36327"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/36328"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=36327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=36327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=36327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}