{"id":36345,"date":"2014-09-11T04:32:30","date_gmt":"2014-09-11T02:32:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/scuola-diego-bouche-e-il-nuovo-direttore-generale-dell-usr-per-la-calabria\/"},"modified":"2023-01-17T12:59:07","modified_gmt":"2023-01-17T11:59:07","slug":"15924-scuola-diego-bouche-e-il-nuovo-direttore-generale-dell-usr-per-la-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15924-scuola-diego-bouche-e-il-nuovo-direttore-generale-dell-usr-per-la-calabria\/","title":{"rendered":"Scuola, Diego Bouch\u00e8 \u00e8 il nuovo direttore generale dell\u2019USR per la Calabria"},"content":{"rendered":"<p>CATANZARO &#8211; Diego Bouch\u00e8 \u00e8 il nuovo Direttore Generale dell\u2019Ufficio Scolastico Regionale per la Calabria.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La cerimonia di insediamento si \u00e8 svolta ieri nella sede di Via Lungomare a Catanzaro Lido. Bouch\u00e8 arriva dall\u2019USR per la Campania dove, ha ricoperto negli ultimi tre anni lo stesso incarico. Il Direttore Diego Bouch\u00e8 ha percorso tutte le tappe professionali nel MIUR, dopo essersi laureato in ingegneria meccanica e abilitato alla professione. Ha insegnato negli istituti di secondo grado, nel 1984 ha superato il concorso nazionale a Dirigente Scolastico e nel 1988 quello a Ispettore Tecnico per le materie tecnologiche e per quelle artistiche. Molti gli incarichi ricoperti, in ambito professionale e accademico. &#8220;Il territorio della Calabria mi \u00e8 caro &#8211; ha dichiarato Bouch\u00e8 nel suo discorso di saluto &#8211; sia per antiche memorie familiari, sia per le radici culturali che mi legano alla terra in cui hanno soggiornato le pi\u00f9 illustri testimonianze della nostra antica civilt\u00e0. Spero &#8211; ha dichiarato &#8211; di poter spendere proficuamente a servizio della regione Calabria, le mie energie e le mie competenze, al fine di continuare un lungo cammino sicuramente non facile. Il percorso che sto per intraprendere &#8211; ha concluso &#8211; mi stimoler\u00e0 ad impegnarmi al massimo delle mie capacit\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Diego Bouch\u00e8 \u00e8 il nuovo Direttore Generale dell\u2019Ufficio Scolastico Regionale per la Calabria.<\/p>\n","protected":false},"author":19,"featured_media":36346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-36345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=36345"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/36346"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=36345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=36345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=36345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}