{"id":36407,"date":"2014-09-12T10:39:16","date_gmt":"2014-09-12T08:39:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/cappellacci-il-vero-cosenza-ci-vorra-ancora-del-tempo\/"},"modified":"2023-01-17T12:59:10","modified_gmt":"2023-01-17T11:59:10","slug":"15955-cappellacci-il-vero-cosenza-ci-vorra-ancora-del-tempo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15955-cappellacci-il-vero-cosenza-ci-vorra-ancora-del-tempo\/","title":{"rendered":"Cappellacci: il vero Cosenza? Ci vorr\u00e0 ancora del tempo"},"content":{"rendered":"<p>COSENZA &#8211; Cos\u00ec il tecnico abruzzese in sala stampa che poi aggiunge; dobbiamo salvarci e preferisco i risultati al bel gioco. Non parlo pi\u00f9 di mercato perch\u00e9 vi ho gi\u00e0 detto come la penso. Su Fornito: arriver\u00e0 il suo momento deve avere pazienza. A Barletta sar\u00e0 una partita tosta ma daremo il massimo come sempre<\/p>\n<p>  <!--more-->  <\/p>\n<p>Nella conferenza stampa del venerd\u00ec Roberto Cappellacci \u00e8 sceso nella sala stampa Bergamini ed ha iniziato a parlare spiegando ai cronisti come ha visto la squadra nella prime due partite e che indicazioni ha tratto da questo inizio di campionato. \u201c<em>Dobbiamo fare del nostro meglio per capire che squadra siamo; se diamo tutti il massimo lo capiremo tra 7 o 8 partite, allora potremo dire qual \u00e8 il vero Cosenza. Se invece molliamo \u00e8 facile ritrovarci in zona retrocessione. Quella di domani a Barletta non rappresenta di sicuro la partita che ci dir\u00e0 se siamo forti o scarsi, ma ci troveremo ad affronteremo una squadra forte e gi\u00e0 affiatata, mentre noi ancora dobbiamo trovare una nostra identit\u00e0, visto che siamo tutti nuovi e con alcuni giocatori che sono anche all\u2019esordio in Lega Pro. Dobbiamo dimostrare tanto, visto che veniamo da serie minori. Certo ci teniamo a giocare bene, a fare vedere un calcio divertente e occorre restare sempre concentrati in tutte le partite, ma sinceramente preferisco giocare male e fare pi\u00f9 punti possibile per salvarci\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Poi il mister passa ad analizzare la gara di domani in Puglia e ritorna sull\u2019argomento Giusppe Fornito, il baby talento mai schierato e che molti tifosi vorrebbero vedere titolare.<\/strong> <em>&#8220;La partita di Barletta per quello che sono le mie sensazioni \u00e8 difficile, perch\u00e9 loro hanno fatto lo scorso anno un campionato sotto tono, invece quest\u2019anno si sono attrezzati per far un campionato da protagonisti. E\u2019 una squadra che ha fisicit\u00e0, ha corsa, tecnica, \u00e8 forte nel reparto offensivo e ci pu\u00f2 mettere in difficolt\u00e0<\/em>. <em>Per quanto riguarda Fornito<\/em> &#8211; aggiunge Cappellacci &#8211; <em>\u00e8 alla pari con tutti gli altri giocatori. Ha grandi qualit\u00e0, \u00e8 un ragazzo che si allena bene ed \u00e8 voglioso, ma deve aspettare il momento giusto senza abbattersi se non gioca. Anche perch\u00e9 passare da panchinaro a titolare inamovibile il passo \u00e8 breve<\/em>.<em> La squadra che scender\u00e0 in campo? So che volete saperlo ogni volta, posso dirvi che non ci saranno grossi stravolgimenti rispetto a domenica, anzi quasi nulla, fatta eccezione per l\u2019infortunato Sperotto ed il rientro di Ciancio e torneremo al 4 3 3&#8243;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong> Chiusura dedicata la mercato. Il DS Meluso \u00e8 tornato al lavoro per cercare di reperire (nel mercato degli svincolati) quel centrocampista richiesto dal tecnico che ci ha tenuto a chiarire<\/strong>. <em>&#8220;L\u2019ho detto la scorsa settimana che la squadra \u00e8 incompleta ma no voglio tornare sull\u2019argomento visto che se ne sta gi\u00e0 parlando troppo ed io non cambio idea. Ma questo non significa che non sia in sintonia con la societ\u00e0. Addirittura ho letto che Meluso non vuol comprare i giocatori a Cappellacci. Non \u00e8 vero e lo ribadisco, questo \u00e8 un ambiente dove si va tutti d\u2019accordo e c\u2019\u00e8 massima disponibilit\u00e0 anche con Guarascio. Se poi la societ\u00e0 non vuole prendere nessuno come avete scritto, vi posso dire che non \u00e8 vero, anche perch\u00e9 \u00e8 sotto gli occhi di tutti che siamo in pochini per 38 partite e se ci sar\u00e0 da prendere qualcuno, il presidente si far\u00e0 trovare pronto&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Cos\u00ec il tecnico abruzzese in sala stampa che poi aggiunge; dobbiamo salvarci e preferisco i risultati al bel gioco. Non parlo pi\u00f9 di mercato perch\u00e9 vi ho gi\u00e0 detto come la penso. Su Fornito: arriver\u00e0 il suo momento deve avere pazienza. A Barletta sar\u00e0 una partita tosta ma daremo il massimo come sempre<\/p>\n","protected":false},"author":23,"featured_media":36408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-36407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=36407"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/36408"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=36407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=36407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=36407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}