{"id":36457,"date":"2014-09-14T06:31:46","date_gmt":"2014-09-14T04:31:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/conzativicci-l-epilogo-guarda-le-foto-esclusive\/"},"modified":"2023-01-17T12:59:13","modified_gmt":"2023-01-17T11:59:13","slug":"15982-conzativicci-l-epilogo-guarda-le-foto-esclusive","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/15982-conzativicci-l-epilogo-guarda-le-foto-esclusive\/","title":{"rendered":"&#8216;Conzativicci &#8211; L&#8217;epilogo&#8217;, GUARDA LE FOTO ESCLUSIVE"},"content":{"rendered":"<p>COSENZA &#8211; Una piacevole conferma per lo spettacolo di Sergio Crocco alias &#8216;Canaletta&#8217;, che per la seconda volta ha riempito l&#8217;intera curva dello Stadio San Vito.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Tra ospiti ed esibizioni anche di rilievo, come quella di Dario Brunori, lo spettacolo che racconta la pioggia di &#8216;sordi spicci&#8217; che si abbatte sulla citt\u00e0 di Cosenza, con i tutti i suoi esilaranti personaggi ha nuovamente incantato il pubblico cosentino. Un nuovo sold out, un nuovo grande successo ma soprattutto l&#8217;orgoglio per Sergio e l&#8217;associazione La Terra di Piero. Della rappresentazione teatrale le nostre pagine hanno parlato tanto e stavolta abbiamo voluto solo immortalare quest&#8217;ultima uscita di Conzativicci&#8230;.ma chiss\u00e0 se non torner\u00e0 a riempire curve e platee. In attesa che il giardiniere poeta, si faccia &#8216;serio&#8217; e presenti il suo nuovo spettacolo &#8220;Seriamente Crocco &#8211; Le opere serie di Canaletta&#8221; il prossimo venerdi 26 Settembre, alle 21.00 al Piccolo Teatro Unical, ecco i particolari scatti che immortalano i momenti pi\u00f9 salienti della serata; immagini che trasudano emozione e che rivelano l&#8217;essenza di personaggi, persone, facce e anime di questo spettacolo che ha conquistato tutti i cosentini.<\/p>\n<p> {imageshow sl=161 sc=3 \/}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Una piacevole conferma per lo spettacolo di Sergio Crocco alias &#8216;Canaletta&#8217;, che per la seconda volta ha riempito l&#8217;intera curva dello Stadio San Vito.<\/p>\n","protected":false},"author":19,"featured_media":36458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-36457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=36457"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/36458"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=36457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=36457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=36457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}