{"id":36555,"date":"2014-09-18T03:47:27","date_gmt":"2014-09-18T01:47:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/padre-fedele-in-cassazione-il-processo-d-appello-e-da-rifare\/"},"modified":"2023-01-17T12:59:23","modified_gmt":"2023-01-17T11:59:23","slug":"16031-padre-fedele-in-cassazione-il-processo-d-appello-e-da-rifare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16031-padre-fedele-in-cassazione-il-processo-d-appello-e-da-rifare\/","title":{"rendered":"Padre Fedele in Cassazione, il processo d&#8217;appello \u00e8 da rifare"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Siamo ampliamente soddisfatti da questo verdetto e riprende la nostra fiducia nella giustizia, che in questa vicenda era andata perduta&#8221;.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Queste le parole del legale di Padre Fedele, l&#8217;avvocato Eugenio Bisceglia, dopo il verdetto della Cassazione che ha annullato con rinvio la condanna a 9 anni e 3 mesi di reclusione, inflittagli dalla Corte d&#8217;Appello di Catanzaro il 17 dicembre 2012. Il processo d&#8217;appello a carico di Padre Fedele Bisceglia, sospeso a divinis nel 2008 in seguito alle pesanti accuse di violenza sessuale su una suora \u00e8 da rifare. Il verdetto \u00e8 stato appena emesso dalla III sezione penale della Cassazione. La Suprema corte ha inoltre annullato solo parzialmente la condanna a 6 anni e 3 mesi di reclusione inflitti in appello ad Antonio Gaudio, segretario di &#8216;padre Fedele&#8217;. La pena, per lui, sar\u00e0 rideterminata da un&#8217;altra sezione della Corte d&#8217;appello di Catanzaro. Ma una parte del suo ricorso \u00e8 stata respinta e dunque passa in giudicato una parte della condanna. In particolare, per quanto riguarda la posizione di Gaudio, la Cassazione ha annullato senza rinvio la condanna limitatamente ad un capo di accusa (capo &#8216;n&#8217;) che per prescrizione e la relativa pena pari ad un mese. Sempre per Gaudio la Cassazione ha annullato con rinvio la condanna limitatamente al capo &#8216;c&#8217; e per la determinazione della pena anche in ordine al capo &#8216;l&#8217;. Il dispositivo che riguarda &#8216;padre Fedele&#8217; \u00e8 molto pi\u00f9 breve: &#8220;Si annulla l&#8217;impugnata sentenza limitatamente ai reati ascritti al Bisceglia e si rinvia ad altra sezione della Corte d&#8217;appello di Catanzaro&#8221;. Il verdetto della Suprema corte \u00e8 stato emesso dopo una lunga camera di consiglio. &#8220;Finalmente per padre Fedele &#8211; ha dichiarato il legale dell&#8217;ex sacerdote &#8211; la Cassazione ha applicato le norme del diritto che in questo processo non sono mai state rispettate&#8221;. Padre Fedele ieri, ha trascorso la giornata in preghiera in chiesa Padre Fedele, e oggi, dopo la decisione della Cassazione sottolinea: &#8220;Io l&#8217;ho sempre detto che sono innocente. Ora dovro&#8217; ricominciare a gridarlo ancora piu&#8217; forte &#8211; dice l&#8217;ex frate &#8211; ma forse stavolta saro&#8217; ascoltato&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Siamo ampliamente soddisfatti da questo verdetto e riprende la nostra fiducia nella giustizia, che in questa vicenda era andata perduta&#8221;.<\/p>\n","protected":false},"author":19,"featured_media":36556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-36555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=36555"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/36555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/36556"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=36555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=36555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=36555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}