{"id":37091,"date":"2014-10-06T10:35:44","date_gmt":"2014-10-06T08:35:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/italcementi\/"},"modified":"2023-01-17T13:00:00","modified_gmt":"2023-01-17T12:00:00","slug":"16303-italcementi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16303-italcementi\/","title":{"rendered":"Sciopero Italcementi, l&#8217;azienda mette in cassa integrazione 80 operai"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>CASTROVILLARI (CS) &#8211; Pare abbia vinto l&#8217;appalto per il terzo macrolotto dell&#8217;A3, ma nonostante ci\u00f2 intende mettere alla gogna i propri dipendenti.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Sono in sciopero da stamane gli ottanta dipendenti dello stabilimento Italcementi di Castrovillari. I lavoratori, sostenuti dai rappresentanti sindacali di Fillea Cgil e Filca Cisl, protestano contro la decisione assunta dai vertici nazionali dell&#8217;azienda di mettere le maestranze dello stabilimento calabrese in cassa integrazione fino al 31 gennaio. Per gioved\u00ec, in Prefettura a Cosenza, \u00e8 fissato un incontro a cui parteciperanno l&#8217;Ente parco del Pollino, le amministrazioni comunali di Castrovillari, Civita e Frascineto, i sindacati e i vertici di Italcementi. Per l&#8217;occasione l&#8217;azienda dovrebbe rendere noto il proprio Piano industriale.<\/p>\n<p>&nbsp;<\/p>\n<p>Italcementi, dopo aver chiuso lo stabilimento di Vibo pare sia stata coinvolta con lo stabilimento di Castrovillari in due grandi investimenti che l&#8217;Anas sta realizzando: i lavori del terzo macrolotto dell&#8217; A3, (Campotenese &#8211; Laino) e i lavori di riammodernamento della Firmo &#8211; Sibari. La protesta continuer\u00e0 fino a quando i vertici aziendali non daranno risposte esaustive ai propri dipendenti. Intanto la dirigenza si difende affermando che:&nbsp;&#8220;l&#8217;attuale condizione del mercato del cemento, che \u00e8 crollato ai livelli del secondo dopoguerra, ha portato la cementeria di Castrovillari alla sospensione temporanea dell&#8217;attivit\u00e0 di cottura, fino al termine dell&#8217;anno, facendo ricorso alla cassa integrazione per una parte del personale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; CASTROVILLARI (CS) &#8211; Pare abbia vinto l&#8217;appalto per il terzo macrolotto dell&#8217;A3, ma nonostante ci\u00f2 intende mettere alla gogna i propri dipendenti.<\/p>\n","protected":false},"author":22,"featured_media":37092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-37091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=37091"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37092"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=37091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=37091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=37091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}