{"id":37276,"date":"2014-10-19T04:00:00","date_gmt":"2014-10-19T02:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/continua-la-campagna-recoil-l-olio-da-cucina-si-trasforma-in-biodiesel\/"},"modified":"2023-01-17T13:00:10","modified_gmt":"2023-01-17T12:00:10","slug":"16403-continua-la-campagna-recoil-l-olio-da-cucina-si-trasforma-in-biodiesel","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16403-continua-la-campagna-recoil-l-olio-da-cucina-si-trasforma-in-biodiesel\/","title":{"rendered":"Continua la campagna Recoil, l&#8217;olio da cucina si trasforma in biodiesel"},"content":{"rendered":"<p>CASTROVILLARI (CS) \u2013 Terzo appuntamento di promozione dei progetti di riciclo avviati nella popolosa cittadina del Pollino.<\/p>\n<p>  <!--more-->  <\/p>\n<p>RECOIL e \u201cIo faccio la differenza\u201d, le iniziative itineranti del Comune di Castrovillari finalizzate alla promozione della raccolta degli oli esausti da cucina e alla differenziata giungono alla terza tappa. All\u2019evento di oggi, 19 Ottobre presso il Protoconvento di Castrovillari, parteciper\u00e0 lo staff di ALESSCO per promuovere le iniziative in corso. Dopo la tappa nel \u201cRione Civita\u201d e nella zona \u201cOrto di Gallo\u201d gli stand informativi saranno presenti all\u2019interno del Calabria Teatro Festival dalle 18 alle 21. A dialogare e confrontarsi con cittadini sui temi della raccolta differenziata sar\u00e0 Franco Bianchimani direttore dell\u2019ufficio ambiente. In particolare spiegher\u00e0 come il comune di Castrovillari, attraverso le azioni intraprese \u00e8 divenuto esempio per gli altri comuni della regione per raccolta dell\u2019olio esausto grazie ad ALESSCO e al suo progetto Recoil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) \u2013 Terzo appuntamento di promozione dei progetti di riciclo avviati nella popolosa cittadina del Pollino.<\/p>\n","protected":false},"author":22,"featured_media":37277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-37276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=37276"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37277"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=37276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=37276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=37276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}