{"id":37449,"date":"2014-10-26T06:05:01","date_gmt":"2014-10-26T05:05:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/anas-modifiche-alla-viabilita-a-partire-da-domani-anche-sulla-ss-18\/"},"modified":"2023-01-17T13:00:20","modified_gmt":"2023-01-17T12:00:20","slug":"16491-anas-modifiche-alla-viabilita-a-partire-da-domani-anche-sulla-ss-18","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16491-anas-modifiche-alla-viabilita-a-partire-da-domani-anche-sulla-ss-18\/","title":{"rendered":"Anas, modifiche alla viabilit\u00e0 a partire da domani sulla SS 18"},"content":{"rendered":"<p>COSENZA &#8211; L\u2019Anas ha comunicato modifiche alla viabilit\u00e0 sulla Statale 18 Tirrena Inferiore a partire da domani.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Per lavori di asfaltatura infatti, da luned\u00ec 27 e fino a venerd\u00ec 31 ottobre 2014, sar\u00e0 chiusa al traffico la strada statale 18 \u201cTirrena Inferiore\u201d dal km 302,600 al km 306,600, nei territori comunali di Fuscaldo e Cetraro, in provincia di Cosenza. I veicoli saranno deviati sulla strada statale 283 dir (ex SS18) e sulla SP 34. Inoltre, nell\u2019ambito degli stessi lavori, sar\u00e0 istituito il senso unico alternato regolamentato da impianto semaforico dal km 297,400 al km 297,600 all\u2019imbocco della galleria San Pietro e Paolo all\u2019interno della variante all\u2019abitato di Guardia Piemontese.<\/p>\n<p>Sempre da luned\u00ec 27 ottobre e fino a sabato 15 novembre 2014, per alcuni lavori, sar\u00e0 istituito un senso unico alternato dal km 509,000 al km 509,400 sulla strada statale 18 \u201cTirrena Inferiore\u201d nel territorio comunale di Scilla, in provincia di Reggio Calabria. Il provvedimento si rende necessario per consentire i lavori di ripristino della rete metallica a margine della sede stradale all\u2019altezza dell km 509,200.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L\u2019Anas ha comunicato modifiche alla viabilit\u00e0 sulla Statale 18 Tirrena Inferiore a partire da domani.<\/p>\n","protected":false},"author":22,"featured_media":37450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-37449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=37449"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37450"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=37449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=37449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=37449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}