{"id":3749,"date":"2012-09-15T10:40:27","date_gmt":"2012-09-15T08:40:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3749"},"modified":"2023-01-17T13:36:38","modified_gmt":"2023-01-17T12:36:38","slug":"848-calcio-al-san-vito-arriva-il-noto-rifinitura-a-porte-chiuse","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/848-calcio-al-san-vito-arriva-il-noto-rifinitura-a-porte-chiuse\/","title":{"rendered":"Calcio, al San Vito arriva il Noto. Rifinitura a porte chiuse"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><span style=\"font-family: Times;\">COSENZA \u2013 <\/span><\/strong>Gagliardi \u201cblinda\u201d il suo Cosenza. Per preparare al meglio la sfida interna con il Noto e tenere tutti i giocatori sulla corda, Gianluca Gagliardi ha deciso di disputare la rifinitura a porte chiuse. Una scelta dettata non solo dalla necessit\u00e0 di tenere alta la concentrazione della squadra, ma anche per la voglia di modificare l\u2019aspetto tattico della sua squadra, lontano da \u201cocchi indiscreti\u201d.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Per affrontare i siciliani, il tecnico rossobl\u00f9, da autentico perfezionista, vuole una squadra in grado di modellarsi in corso d\u2019opera sul piano tattico, passando all\u2019occorrenza dal 3-5-2 ad un pi\u00f9 offensivo 3-4-3, senza dimenticare altre formule tecnico-tattiche. I giocatori in rosa, permettono al trainer silano, diverse soluzioni, sia come impostazione di gioco, che come \u201crobustezza\u201d psicologica. Per domani, nell\u2019elenco dei convocati figurano venti giocatori. Non fanno parte del gruppo l\u2019acciaccato Sicignano, il centrocampista Benincasa, costretto per un turno dal giudice sportivo ad indossare abiti borghesi. Il \u201cfulmine\u201d Andrea Marano, dopo il leggero infortunio, \u00e8 apparso in pieno recupero. Non si sa se il tecnico lo schierer\u00e0 sin dal primo minuto o nel corso della partita. E\u2019 questo, infatti, l\u2019unico dubbio che Gagliardi si porta dietro. Per il resto la formazione \u00e8 pressocch\u00e8 fatta: Straface in porta, retroguardia a tre con Bruno e Parenti laterali e capitan Parisi centrale, Fiore, Salvino, Pesce e Varriale, chiamati a costruire le trame offensive e dare palloni invitanti in area per Le Piane e Arcidiacono, sulle fasce e Mosciaro ariete centrale. Contro il Noto, Gagliardi vuole vede quel Cosenza cinico, spietato, arrembante che ha sciorinato buon calcio al \u201cTupparello\u201d di Acireale. Oltre che conferme sul piano tattico, il tranier silano si aspetta anche di vedere una maggiore fluidit\u00e0 di manovra negli ultimi sedici metri, finora unico tasto dolente mostrato dalla squadra nel corso di queste prime tre partite. La gara non si presenta per niente facile, considerando che il Noto, domenica scorsa, ha perso contro il Messina solo all\u2019ultimo assalto dei giallorossi. Il Cosenza, inoltre, si presenta davanti al pubblico amico con una nuova veste: sulla maglia rossobl\u00f9, infatti compariranno i nomi degli sponsor che hanno deciso di vestire ed investire sul Cosenza: Oro Cash e Precenzano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Gagliardi \u201cblinda\u201d il suo Cosenza. Per preparare al meglio la sfida interna con il Noto e tenere tutti i giocatori sulla corda, Gianluca Gagliardi ha deciso di disputare la rifinitura a porte chiuse. Una scelta dettata non solo dalla necessit\u00e0 di tenere alta la concentrazione della squadra, ma anche per la voglia di [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":1421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,5,20],"tags":[],"class_list":["post-3749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-old","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3749"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/1421"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}