{"id":37606,"date":"2014-10-30T06:53:33","date_gmt":"2014-10-30T05:53:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/a-cosenza-il-progetto-ristorando-per-aiutare-i-nuovi-poveri\/"},"modified":"2023-01-17T13:00:28","modified_gmt":"2023-01-17T12:00:28","slug":"16573-a-cosenza-il-progetto-ristorando-per-aiutare-i-nuovi-poveri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16573-a-cosenza-il-progetto-ristorando-per-aiutare-i-nuovi-poveri\/","title":{"rendered":"A Cosenza il progetto &#8216;Ristorando&#8217; per aiutare i &#8216;nuovi poveri&#8217;"},"content":{"rendered":"<p>COSENZA &#8211; E&#8217; stato presentato a Cosenza il progetto \u201cRistorando\u201d, promosso dalla rete solidale del volontariato, insieme al Comune, per aiutare i \u201cnuovi poveri\u201d.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Chi sono? singoli o famiglie che non riescono ad arrivare a fine mese e che versano in situazioni di difficolt\u00e0 temporanea, a causa della crisi economica. E &#8216;Ristorando&#8217; si rivolge proprio alle nuove sacche di povert\u00e0. Promosso dal M.E.D.A. Calabria (Movimento Europeo Diversabili Associati) in partenariato con altre sette associazioni di volontariato, il progetto sperimentale ed innovativo e finanziato dal Ministero del lavoro e delle politiche sociali, \u00e8 stato presentato al Chiostro di S.Domenico in una conferenza stampa alla quale hanno preso parte l\u2019Assessore alla solidariet\u00e0 e coesione sociale Manfredo Piazza, la responsabile di \u201cRistorando\u201d Flora Barone, Susanna Giovannini, referente Formazione e Rappresentanza della rete \u201cRistorando\u201d, Gian Marco Guglielmo, referente del gruppo di giovani volontari impegnati nella rete e, in rappresentanza del Centro servizi per il volontariato, la Vice Presidente Isabella Manna.<\/p>\n<p>&nbsp;<\/p>\n<p>Il progetto prevede una prima fase di ascolto delle persone in difficolt\u00e0 in punti di accoglienza o sportelli di ascolto dislocati sul territorio, con la presa in carico del soggetto o della famiglia che vengono avviati ad un percorso di vita e, successivamente, su specifica richiesta, l\u2019assegnazione al servizio \u201cRistorando\u201d, dove le persone in difficolt\u00e0 possono recarsi a mangiare senza pensare di consumare il pasto ad una mensa sociale. Obiettivo finale \u00e8 quello del reinserimento dei soggetti in stato di disagio, al fine di tutelare il bene e l\u2019unit\u00e0 della famiglia. Il sostegno accordato varier\u00e0, a seconda dei casi, da uno a tre mesi, cos\u00ec da non degenerare in mensa assistenzialistica. Il progetto si prefigge di recuperare un minimo di 60 persone o 30 famiglie nell\u2019arco di 12 mesi.&nbsp;Al servizio \u201cRistorando\u201d, che \u00e8 allocato in Via Popilia, nei pressi del Palazzetto dello sport, possono accedere: i cittadini italiani che risiedono a Cosenza, single o famiglie, specie se con minori a carico, lavoratori che soffrono un disagio economico, disoccupati temporanei con o senza sostegni al reddito, anziani o disabili con pensioni al minimo. I<span style=\"font-size: 11.8181819915771px; line-height: 1;\">l progetto, coinvolge circa 70 volontari.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 11.8181819915771px; line-height: 1;\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; E&#8217; stato presentato a Cosenza il progetto \u201cRistorando\u201d, promosso dalla rete solidale del volontariato, insieme al Comune, per aiutare i \u201cnuovi poveri\u201d.<\/p>\n","protected":false},"author":22,"featured_media":37607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-37606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=37606"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37607"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=37606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=37606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=37606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}