{"id":37699,"date":"2014-11-03T09:55:39","date_gmt":"2014-11-03T08:55:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/tenta-di-togliersi-la-vita-42enne-bloccato-sull-a3\/"},"modified":"2023-01-17T13:00:33","modified_gmt":"2023-01-17T12:00:33","slug":"16620-tenta-di-togliersi-la-vita-42enne-bloccato-sull-a3","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16620-tenta-di-togliersi-la-vita-42enne-bloccato-sull-a3\/","title":{"rendered":"Tenta di togliersi la vita, 42enne bloccato sull&#8217;A3"},"content":{"rendered":"<p>COSENZA &#8211; Faceva avanti e indietro in autostrada in evidente stato confusionale fra gli svincoli di Tarsia e Rogliano (CS).<\/p>\n<p>  <!--more-->  <\/p>\n<p>Protagonista un 42enne di Cosenza, M. V. queste le sue iniziali, che ha tentato di togliersi la vita. A notarlo per\u00f2, alcuni automobilisti che si sono accorti del fatto che la sua automobile continuava a camminare nonostante le gomme fossero bucate. Allertate le forze dell&#8217;ordine, \u00e8 intervenuta una pattuglia della polstrada e, dopo pochi minuti, l&#8217;uomo \u00e8 stato raggiunto nei pressi di Tarsia e fermato. Ma alla vista dei poliziotti, il 42enne \u00e8 andato in escandescenza e dopo aver preso un coltello ha provato a tagliarsi le vene davanti ai militari. Gli agenti per fortuna hanno evitato il peggio e il 42enne \u00e8 stato trasportato all\u2019ospedale civile dell\u2019Annunziata per i dovuti accertamenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Faceva avanti e indietro in autostrada in evidente stato confusionale fra gli svincoli di Tarsia e Rogliano (CS).<\/p>\n","protected":false},"author":22,"featured_media":37700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-37699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=37699"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37700"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=37699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=37699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=37699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}