{"id":3772,"date":"2012-09-16T11:02:13","date_gmt":"2012-09-16T09:02:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3772"},"modified":"2023-01-17T13:36:41","modified_gmt":"2023-01-17T12:36:41","slug":"875-calcio-zamparini-deluso-dal-suo-palermo-e-da-sannino-arriva-reja","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/875-calcio-zamparini-deluso-dal-suo-palermo-e-da-sannino-arriva-reja\/","title":{"rendered":"Calcio, Zamparini deluso dal suo Palermo e da Sannino. Arriva Reja?"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>PALERMO &#8211; <\/b>Sannino \u00e8 gi\u00e0 in bilico e la notte decider\u00e0 del suo destino. Ma i segnali per lui sono tutti negativi. Zamparini non era al Barbera, ma a cena a Trieste. Prima ha fatto sapere di non avere visto la partita, e di non voler al momento pensare a niente.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Poi, pressato dai gornalisti nell&#8217;immediata dopo partita, ha confessato: \u00abSono amareggiato e preoccupato di retrocedere, pensavo di vincere, sarebbe stato importante per il morale. Stanotte vedr\u00f2 la partita, gi\u00e0 alcuni amici mi hanno raccontato che \u00e8 stata brutta. Se penso all\u2019esonero? Adesso preferisco ubriacarmi che rispondere a questa domanda\u00bb.<br \/><b>CANDIDATURE &#8211; <\/b>La situazione insomma \u00e8 pesante ed anche il Dg Perinetti \u00e8 in attesa di comunicazioni. Ma i primi nomi di possibili sostituti sono gi\u00e0 trapelati. Il favorito numero 1 per l\u2019eventuale cambio \u00e8 Edy Reja, friulano come il patron, uomo d\u2019esperienza, legato a Palermo da affetto per averla conosciuta da calciatore. Reja peraltro era gi\u00e0 ai primi posti della lista di Zamparini che poi vir\u00f2 su Sannino. Un uomo d\u2019esperienza (67 anni) per rimettere in piedi un caso delicato. Reja per\u00f2 sarebbe in questo momento tentato da una proposta estera. Non trova grandi conferme l\u2019idea Gasperini, con cui il presidente ebbe un abboccamento non felice l\u2019estate scorsa. Solo una suggestione il clamoroso ritorno di Delio Rossi, amatissimo dalla piazza: riannodare i fili del rapporto umano fra i due appare quasi impossibile. Pi\u00f9 credibile l\u2019ipotesi Ballardini, anche in questo caso un deja vu per un tecnico ben voluto e con cui la squadra gioc\u00f2 un ottimo calcio. Ma con Zamparini tutto \u00e8 possibile. Anche una ulteriore fiducia a Sannino cui alla vigilia era stato detto di stare tranquillo: \u00abResta anche se perde le prossime due gare\u00bb, aveva sancito il presidente.<\/p>\n<p style=\"text-align: justify;\"><b>SANNINO:<\/b> \u00abMi dispiace che i ragazzi siano usciti tra i fischi, perch\u00e9 hanno dato tutto quello che potevano. Ci hanno rimontato in un momento in cui stavamo concretizzando un risultato importante. Stasera mi \u00e8 piaciuta l&#8217;organizzazione messa in campo, abbiamo disputato la nostra partita, i risultati contano, ma si va avanti. Zamparini? Io non sono tranquillo, sono sereno. Sono sette anni che sono sereno. Sette anni di gioia, ed anche stasera sono felice per come i ragazzi hanno interpretato la gara. Capisco che il compito di voi giornalisti \u00e8 di andare oltre il campo, ma credo che il Palermo e Zamparini che esonera allenatore sia un telenovela che dura da troppo. Quello che stato fatto dall&#8217;arbitro va bene &#8211; dice -. Alla fine non dobbiamo cercare alibi per un risultato che non siamo riusciti a portare a casa. In classifica abbiamo fatto un punto, mosso la classifica. Certo ne potevamo fare tre, per\u00f2, questa sera abbiamo pagato a caro prezzo un piccolo errore\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PALERMO &#8211; Sannino \u00e8 gi\u00e0 in bilico e la notte decider\u00e0 del suo destino. Ma i segnali per lui sono tutti negativi. Zamparini non era al Barbera, ma a cena a Trieste. Prima ha fatto sapere di non avere visto la partita, e di non voler al momento pensare a niente.<\/p>\n","protected":false},"author":22,"featured_media":1467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,5,20],"tags":[],"class_list":["post-3772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-old","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3772"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/1467"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}