{"id":37790,"date":"2014-11-06T08:49:43","date_gmt":"2014-11-06T07:49:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/rifiuti-abbancati-nelle-cupole-geodetiche-litigano-occhiuto-e-i-cinque-stelle\/"},"modified":"2023-01-17T13:00:38","modified_gmt":"2023-01-17T12:00:38","slug":"16665-rifiuti-abbancati-nelle-cupole-geodetiche-litigano-occhiuto-e-i-cinque-stelle","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16665-rifiuti-abbancati-nelle-cupole-geodetiche-litigano-occhiuto-e-i-cinque-stelle\/","title":{"rendered":"Rifiuti abbancati nelle cupole geodetiche, acceso dibattito tra Occhiuto e i Cinque Stelle"},"content":{"rendered":"<p>COSENZA &#8211; Botta e risposta sul deposito temporaneo nello spazio fieristico dettato dall&#8217;emergenza rifiuti.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Pubblichiamo di seguito il testo integrale in cui i grillini muovono le proprie critiche alla scelta di far permanere nei cassoni per 72 ore la spazzatura raccolta in strada e la risposta fornita dal presidente della Provincia nonch\u00e8 Sindaco di Cosenza.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;ATTACCO DEL DEPUTATO SEBASTIANO BARBANTI<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Il piazzale delle cupole geodetiche, l\u2019ex fiore all\u2019occhiello dello spazio espositivo dell\u2019area urbana e oltre, viene utilizzato per stoccare i rifiuti di Cosenza. I container hanno preso il posto che una volta era riservato alle aziende e il cattivo odore si sprigiona, nquinando l&#8217;aria della citt\u00e0 e delle vicine Rende e Castrolibero. Il sindaco Occhiuto, nonch\u00e9 neo presidente della Provincia di Cosenza, dovrebbe dare spiegazioni immediate ai cittadini dell\u2019hinterland: <strong>ma veramente non c&#8217;era luogo migliore per tale scopo? <\/strong>Soprattutto ove si consideri che lo stesso era in procinto di essere riqualificato e dovr\u00e0, comunque, essere bonificato se si vuole che ridiventi il simbolo delle fiere espositive della piccola e media impresa calabrese.<\/p>\n<p>&nbsp;<\/p>\n<p>Dal voler realizzare un Centro di riciclo sul modello di Vedelago a Cosenza all&#8217;improvvisazione di un centro di stoccaggio di rifiuti il passo ci sembra molto lungo. Come Movimento 5 Stelle non possiamo che censurare una scelta miope quale quella effettuata dall\u2019amministratore cosentino, sicuramente dispendiosa per il futuro intervento pubblico. Il primo cittadino Occhiuto spieghi alla citt\u00e0 i motivi di questa operazione poco chiara.<strong> Secondo noi non esistono in quei luoghi gli standard minimi di sicurezza per poter stoccare rifiuti di dubbia provenienza ma accettiamo smentite.<\/strong> Una cosa \u00e8 certa: mai come in questo caso urge un\u2019operazione trasparenza che possa tranquillizzare la citt\u00e0 oltre che i residenti della zona&#8221;.<br \/>&nbsp;<br \/>I CHIARIMENTI DEL SINDACO MARIO OCCHIUTO<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cL\u2019operazione-verit\u00e0 invocata al sottoscritto dall\u2019onorevole Barbanti \u00e8 a portata di tutti e risiede nel virtuosismo che la citt\u00e0 di Cosenza ha dimostrato rispetto alle buone pratiche urbane e, nella fattispecie, al ciclo dei rifiuti. Cosenza in fatto di raccolta differenziata \u00e8 diventata un modello per l\u2019intera Calabria oltre che per il Meridione. <strong>Risulta infatti fra i pochissimi Comuni del sud Italia ad aver raggiunto la percentuale del 60% grazie alla determinazione dell\u2019Esecutivo.<\/strong> <strong>Il nostro obiettivo, com\u2019\u00e8 noto, \u00e8 quello di puntare al traguardo dei rifiuti-zero<\/strong> e sono certo che riusciremo a conseguirlo. Gli esponenti del Movimento 5 Stelle, fra l\u2019altro spesso al nostro fianco in iniziative legate alla tutela dell\u2019ambiente ed alle relative attivit\u00e0 a salvaguardia della salute dei cittadini, sono a conoscenza delle azioni dell\u2019Amministrazione municipale per realizzare, nonostante la bocciatura dei finanziamenti da parte della Regione Calabria, il Centro Mercato del Riciclo proprio a Cosenza.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019attuazione del progetto \u00e8 in dirittura d\u2019arrivo. <strong>I nostri sforzi in tal senso hanno consentito, negli ultimi dieci giorni di blocco dei conferimenti dell\u2019indifferenziata causati dalla chiusura degli impianti, che i cittadini non risentissero dell\u2019ennesima emergenza.<\/strong> Ed \u00e8 per questo motivo che \u00e8 nata l\u2019esigenza dell\u2019ordinanza sindacale che vede l\u2019area delle cupole geodetiche come area di stoccaggio temporaneo. Per la prima volta il problema dei rifiuti \u00e8 stato affrontato con criterio e con lo scopo di ridurre l\u2019inquinamento del sottosuolo, <strong>monitorando la situazione circoscritta alla zona delle cupole anzich\u00e9 consentendo che la totalit\u00e0 del territorio urbano diventasse una enorme discarica.<\/strong> Il processo virtuoso che abbiamo innescato, dunque, ci ha consentito sia la drastica riduzione della produzione di rifiuti e sia di fronteggiare l\u2019ultimo momento di criticit\u00e0 dovuto ai blocchi continuati e continuativi degli impianti\u201d. <span style=\"font-size: 14pt; font-family: Tahoma;\">&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Botta e risposta sul deposito temporaneo nello spazio fieristico dettato dall&#8217;emergenza rifiuti.<\/p>\n","protected":false},"author":22,"featured_media":37791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-37790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=37790"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37791"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=37790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=37790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=37790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}