{"id":37898,"date":"2014-11-10T08:22:49","date_gmt":"2014-11-10T07:22:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/santa-natuzza\/"},"modified":"2023-01-17T13:00:44","modified_gmt":"2023-01-17T12:00:44","slug":"16720-santa-natuzza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16720-santa-natuzza\/","title":{"rendered":"Mamma Natuzza sar\u00e0 beatificata, la certezza arriva da monsignor Nunnari"},"content":{"rendered":"<p>PARAVATI (VV) &#8211; Nel corso della celebrazione eucaristica di ieri l&#8217;arcivescovo di Cosenza &#8211; Bisignano ha espresso ottimismo per il processo di beatificazione della famosa religiosa di Paravati.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Diverse migliaia di persone si sono ritrovate ieri a Paravati di Mileto in occasione della ricorrenza del 21\/mo anniversario dell&#8217;arrivo a Paravati dell&#8217;effige del Cuore Immacolato di Maria Rifugio delle Anime. A distanza di poco pi\u00f9 di una settimana dalla cerimonia con la quale \u00e8 stato sancito l&#8217;avvio della causa di beatificazione per Natuzza Evolo, la mistica di Paravati, morta nel giorno della festa di tutti i Santi di cinque anni fa, in tanti si sono ritrovati nella frazione del comune del vibonese. Al centro della celebrazione di ieri la statua della Madonna realizzata sulla base delle indicazioni fornite dalla stessa Natuzza Evolo con le fattezze che la madre del Cristo aveva nelle apparizioni rivelate alla mistica. La liturgia \u00e8 stata presieduta da mons. Salvatore Nunnari, presidente della Conferenza episcopale calabra. Presente il vescovo di Mileto, mons. Luigi Renzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PARAVATI (VV) &#8211; Nel corso della celebrazione eucaristica di ieri l&#8217;arcivescovo di Cosenza &#8211; Bisignano ha espresso ottimismo per il processo di beatificazione della famosa religiosa di Paravati.<\/p>\n","protected":false},"author":22,"featured_media":37899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-37898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=37898"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37899"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=37898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=37898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=37898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}