{"id":37946,"date":"2014-11-11T14:31:37","date_gmt":"2014-11-11T13:31:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/settantasette-persone-su-un-natante-in-panne-nei-pressi-di-una-scogliera-tratte-in-salvo\/"},"modified":"2023-01-17T13:00:47","modified_gmt":"2023-01-17T12:00:47","slug":"16744-settantasette-persone-su-un-natante-in-panne-nei-pressi-di-una-scogliera-tratte-in-salvo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16744-settantasette-persone-su-un-natante-in-panne-nei-pressi-di-una-scogliera-tratte-in-salvo\/","title":{"rendered":"Tratte in salvo settantasette persone su un natante in panne nei pressi di una scogliera"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; A bordo anche dei neonati approdati in condizioni estreme sulle coste calabresi.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Settantasette migranti di nazionalit\u00e0 siriana e irachena tra i quali anche dieci minori, alcuni di pochi mesi, sono stati soccorsi nello Jonio su una scogliera a Capo d&#8217;Armi tra Melito Porto Salvo e Reggio Calabria. Le operazioni di recupero dei migranti, 56 uomini e 11 donne, che si trovavano in una zona di non facile raggiungibilit\u00e0 sono state condotte da Guardia costiera, Polizia, Guardia di finanza e Vigili del fuoco e sono state rese difficoltose dal mare mosso. A seguito della richiesta di aiuto giunta alla Direzione marittima da parte di uno dei migranti che comunicava la posizione indicando la vicinanza di un faro, la Guardia costiera ha disposto l&#8217;invio da Reggio Calabria di una motovedetta assieme a personale da terra.<\/p>\n<p>&nbsp;<\/p>\n<p>Verificata l&#8217;impossibilit\u00e0 di raggiungere via terra la scogliera, a picco sul mare, si \u00e8 quindi optato per l&#8217;utilizzo di zattere autogonfiabili in dotazione alle motovedette della Guardia costiera. Le zattere, con l&#8217;ausilio dei sommozzatori dei vigili del fuoco, sono state avvicinate il pi\u00f9 possibile alla scogliera, malgrado il mare mosso, consentendo il recupero dei migranti e il loro successivo trasbordo alle unit\u00e0 navali di Polizia di Stato e Guardia di Finanza giunte sul posto. I migranti sono stati condotti nel porto di Reggio Calabria dove, con il coordinamento della Prefettura, si \u00e8 proceduto all&#8217;identificazione e alla valutazione delle condizioni di salute e al successivo trasferimento in una struttura di prima accoglienza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; A bordo anche dei neonati approdati in condizioni estreme sulle coste calabresi.<\/p>\n","protected":false},"author":22,"featured_media":37947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-37946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=37946"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/37946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/37947"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=37946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=37946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=37946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}