{"id":38105,"date":"2014-11-15T14:31:01","date_gmt":"2014-11-15T13:31:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/finalmente-cosenza-i-rossoblu-schiantano-la-vigor-lamezia-e-tornano-al-successo-3-0\/"},"modified":"2023-01-17T13:00:56","modified_gmt":"2023-01-17T12:00:56","slug":"16825-finalmente-cosenza-i-rossoblu-schiantano-la-vigor-lamezia-e-tornano-al-successo-3-0","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16825-finalmente-cosenza-i-rossoblu-schiantano-la-vigor-lamezia-e-tornano-al-successo-3-0\/","title":{"rendered":"Il Cosenza schianta la Vigor Lamezia e torna al successo (3-0)"},"content":{"rendered":"<p><strong>Partita dominata dai rossoblu che rifilano 3 goal alla Vigor Lamezia giocando una partita perfetta e tornando al successo in casa dopo quasi 9 mesi. La cura Roselli inizia a dare i suoi effetti. Di Fornito nel primo tempo, Calderini e Cori nella ripresa le marcature. Lamezia in 10 nel finale<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA \u2013 Il Cosenza schianta la Vigor Lamezia con un rotondo 3 a 0, vince l\u2019ultimo derby del girone d\u2019andata, ritrova la vittoria in casa dopo quasi 9 mesi ma, soprattutto, si rialza in classifica e si riconcilia con il suo pubblico. Non era un partita facile alla vigilia, ma il Cosenza l\u2019ha fatta diventare semplice, dominando l\u2019incontro in lungo e largo, giocando una gara tatticamente perfetta e senza sbavature, con i reparti tutti ben organizzati e con gli attaccanti rossoblu finalmente decisivi sotto porta. Partita sbloccata al 6\u2019 del primo tempo da una punizione gioiello di Fornito. Nel secondo tempo uno due del Cosenza con Caccetta e Cori che nel giro di due minuti portano a 3 le reti del Cosenza e chiudono l\u2019incontro gi\u00e0 al 7\u2019 del secondo tempo. La Vigor Lamezia? Non pervenuta, ma per gli uomini di mister Erra resta solo una giornata storta che non va a scalfire l\u2019ottimo momento dei biancoverdi. Ora per i lupi la trasferta di Savoia contro un\u2019altra diretta concorrente per la salvezza dove servir\u00e0 confermare la bella prova di questo pomeriggio.<\/p>\n<p><strong>La partita<\/strong> \u2013 Cosenza e Vigor Lamezia tornano ad affrontarsi al San Vito a quasi un anno di distanza. Era il 24 Gennaio del 2014 e fin\u00ec 3 a 0 per i lupi, grazie alla doppietta di De Angelis ed al sigillo finale di Calderini. Quella vittoria permise al Cosenza di riconquistare la vetta della classifica. Situazione diametralmente opposta rispetto a questa stagione, nella quale i lametini guidati da mister Erra navigano nelle zone altissime di classifica sciorinando un ottimo calcio, mente il Cosenza si trova a lottare in piena zona play-out, alla ricerca della prima vittoria casalinga. Rosselli ripropone il 4 4 2 ma, rispetto alla squadra che ha affrontato il Messina 7 giorni fa, effettua alcune modifiche. In mezzo al campo Arrigoni prende il posto di Corsi che si accomoda in panchina, mentre Zanini, rileva Alessandro che finisce addirittura in tribuna. La Vigor Lamezia, con il 4 3 3, \u00e8 in formazione tipo. con Scarsella e Improta a centrocampo pronti a supportare il trio d\u2019attacco con Battaglia, Montella e il capocannoniere Del Sante.<\/p>\n<p><strong>Punizione gioiello di Fornito, Cosenza avanti<\/strong> \u2013 Pronti via e dopo i primi minuti di studio il Cosenza passa in vantaggio. Siamo al 6\u2019 e Calderini si procura un calcio di punizione dal limite dell\u2019area. Sulla palla va Fornito che con un sinistro pennellato aggira la barriera e insacca la palla sotto il sette alla sinistra di Piacenti vanamente proteso in tuffo. Per il giovane centrocampista, che va a raccogliere l\u2019ovazione dei tifosi e dei compagni, \u00e8 il primo goal con la maglia del Cosenza. La Vigor tenta di riorganizzarsi, mentre il Cosenza approfitta degli spazi liberi per ripartire velocemente in contropiede, ma senza frenesia e cercando di gestire la palla con Caccetta e il galvanizzato Fornito, sempre pronti a dettare i ritmi. Al 33\u2019Cori ha sui piedi la palla del raddoppio. L\u2019attaccante direttamente sul rinvio di Ravaglia controlla la palla grazie anche ad un liscio della difesa biancoverde, ma il suo tiro da dentro l\u2019aera piccola viene respinto con un mezzo miracolo da Piacenti. Un minuto dopo ci prova Calderini ma il suo tiro non inquadra la porta. Al 36\u2019per\u00f2 Zanini si fa male alla caviglia e deve lasciare il campo. Al suo posto Blondett che va a destra, Fornito si posta a sinistra e Ciancio che scala avanti in mezzo al campo. Al 41\u2019 si vedono gli ospiti con un velenoso tiro cross di Malerba per poco non sorprende Ravaglia che deve respingere con affanno. La Vigor colleziona 4 angoli nel giro di pochi minuti ma non succede nulla e dopo 3 minuti di recupero finisce il primo tempo.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-36603\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2014\/11\/CoLamezia_3.jpg\" alt=\"CoLamezia 3\" width=\"640\" height=\"427\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Inizio ripresa: uno-due micidiale del Cosenza che chiude la gara\u00a0<\/strong>&#8211; Squadre in campo senza cambi e con la stessa impostazione tattica della prima frazione. Vigor Lamezia in avanti in cerca del pareggio e Cosenza a coprire ogni zona del campo pronto a sfruttare le ripartenze. Su una di questa i lupi trovano immediatamente il raddoppio. Siamo al 50\u2019, Calderini riceve da Arrigoni un ottimo pallone e si invola verso la porta lametina, servizio al bacio per Caccetta che entra un aera di rigore e uccella Piacenti con un tiro che passa sotto le gambe del portiere. Nemmeno il tempo di esultare e il Cosenza fa tris al 52\u2019 con un super goal di Sasha Cori che stoppa in aera e di sinistro batte per la terza volta il portiere biancoverde. Lupi alle stelle e tripudio sugli spalti, Lamezia frastornato e irriconoscibile rispetto alle ultime uscite. La partita si mette in discesa e il Cosenza controlla senza affanno le azioni offensive della Vigor. Al 67\u2019 esordio in campionato per Cesca che rileva un esausto Calderini, mentre Erra toglie il difensore Filosa e inserisce l\u2019attaccante Kostadinovic per avere pi\u00f9 spinta in avanti, ma gli uomini di Roselli non corrono alcun pericolo e portano a casa una vittoria preziosissima. Da segnalare nel finale l\u2019espulsione di Malerba (rosso diretto) per un fallaccio da dietro su Caccetta. Finisce con i giocatori del Cosenza a ricevere l&#8217;ovazione della curva sud.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cosenza \u2013 Vigor Lamezia:<\/strong> 3 -0<\/p>\n<p><strong>Marcator<\/strong>i: 6\u2019 Fornito, 50 Caccetta, 52\u2019 Cori<\/p>\n<p><strong>Cosenza Calcio<\/strong>: Ravaglia, Magli, Ciancio, Sperotto, Tedeschi, Arrigoni, Fornito, Caccetta, Zanini (36\u2019 Blondett), Calderini (67\u2019 Cesca), Cori (75\u2019De Angelis)<br \/>\n<strong>Panchina<\/strong>: Saracco, Blondett, Corsi, Mosciaro, De Angelis, Cesca<br \/>\n<strong>Allenatore<\/strong>: Giorgio Roselli<\/p>\n<p><strong>Vigor Lamezia<\/strong>: Piacenti, Spirito, Filosa(69\u2019 Kostadinovic), Gattari, Malerba, Puccio (75\u2019 Voltasio), Scarsella, Battaglia, Improta, Del Sante, Montella (\u201855Held)<br \/>\n<strong>Panchina:<\/strong> Rosti, Kostadinovic, Rossini, Gimap\u00e0, Voltasio, Catalano, Held<br \/>\n<strong>Allenatore<\/strong>: Alessandro Erra<\/p>\n<p><strong>Arbitro:<\/strong> Signor De Giudici di Latina<\/p>\n<p><strong> Ammoniti<\/strong>: Scarsella (L), Caccetta (C), Gattari(L)<\/p>\n<p><strong>Esplusi<\/strong>: Malerba(V) Angoli: 1 &#8211; 7<\/p>\n<p><strong>Note<\/strong>: Giornata nuvolosa, terreno scivoloso e non in perfetta forma. Spettatori 2.000 circa con una 50 di tifosi del Lamezia nel settore ospiti e un centinaio nella tribuna numerata.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-36604\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2014\/11\/CS_Lamzia_02_articolo.jpg\" alt=\"CS Lamzia 02 articolo\" width=\"640\" height=\"361\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partita dominata dai rossoblu che rifilano 3 goal alla Vigor Lamezia giocando una partita perfetta e tornando al successo in casa dopo quasi 9 mesi. La cura Roselli inizia a dare i suoi effetti. Di Fornito nel primo tempo, Calderini e Cori nella ripresa le marcature. Lamezia in 10 nel finale<\/p>\n","protected":false},"author":23,"featured_media":38106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-38105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=38105"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/38106"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=38105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=38105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=38105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}