{"id":38170,"date":"2014-11-18T06:14:03","date_gmt":"2014-11-18T05:14:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/armi-e-furti-emessi-sei-provvedimenti-cautelari-nel-reggino\/"},"modified":"2023-01-17T13:00:59","modified_gmt":"2023-01-17T12:00:59","slug":"16858-armi-e-furti-emessi-sei-provvedimenti-cautelari-nel-reggino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/16858-armi-e-furti-emessi-sei-provvedimenti-cautelari-nel-reggino\/","title":{"rendered":"Morte Maria Concetta Cacciola, emessi sei provvedimenti cautelari nel Reggino"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; L&#8217;operazione \u00e8 stata avviata questa mattina dai carabinieri del comando provinciale di Reggio Calabria.<\/p>\n<p>  <!--more-->  <\/p>\n<p>I militari hanno dato esecuzione a sei provvedimenti cautelari, emessi dal gip del Tribunale di Palmi, su richiesta della procura della Repubblica di Palmi, diretta dal procuratore Emanuele Crescenti, nei confronti di altrettanti soggetti ritenuti responsabili di detenzione illegale di armi comuni da sparo, furto aggravato e istigazione ad esternare false dichiarazioni davanti al Tribunale. I provvedimenti cautelare sono stati eseguiti nell&#8217;ambito dell&#8217;inchiesta sulla morte di Maria Concetta Cacciola, la testimone di giustizia deceduta nel 2011 dopo avere ingerito acido muriatico. Secondo quanto \u00e8 emerso dalle indagini, Maria Concetta Cacciola, nipote del boss della &#8216;ndrangheta Gregorio Bellocco, sarebbe stata costretta ad ingerire acido muriatico per indurla a ritrattare le accuse di appartenenza alla &#8216;ndrangheta che aveva rivolto ad alcuni suoi familiari. Nell&#8217;inchiesta sono coinvolti anche due avvocati, Gregorio Cacciola e Vittorio Pisani. Quest&#8217;ultimo, da qualche mese, collabora con la giustizia ed \u00e8 proprio dalle sue dichiarazioni che sarebbero scaturiti gli sviluppi investigativi che hanno portato ai nuovi arresti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; L&#8217;operazione \u00e8 stata avviata questa mattina dai carabinieri del comando provinciale di Reggio Calabria.<\/p>\n","protected":false},"author":19,"featured_media":38171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-38170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=38170"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/38171"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=38170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=38170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=38170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}