{"id":38481,"date":"2014-11-29T18:41:10","date_gmt":"2014-11-29T17:41:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/dopo-lo-zecchino-d-argento-secondo-posto-per-sara-la-piccola-cantante-di-castrolibero\/"},"modified":"2023-01-17T13:01:17","modified_gmt":"2023-01-17T12:01:17","slug":"17020-dopo-lo-zecchino-d-argento-secondo-posto-per-sara-la-piccola-cantante-di-castrolibero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/17020-dopo-lo-zecchino-d-argento-secondo-posto-per-sara-la-piccola-cantante-di-castrolibero\/","title":{"rendered":"Dopo lo &#8216;Zecchino d&#8217;argento&#8217; terzo posto per Sara, la piccola cantante di Castrolibero"},"content":{"rendered":"<p>BOLOGNA &#8211; La canzone &#8216;Chi ha paura del buio&#8217; di Edoardo Barchi e Alessia Chianese ha vinto con 199 punti la 57^ edizione dello Zecchino D&#8217;Oro.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Sara Guglielmelli, che ieri \u00e8 stata premiata con lo &#8216;Zecchino d&#8217;argento&#8217;, si \u00e8 piazzata al terzo posto e con la sua canzone intitolata &#8216;Il Domani&#8217;, ha ottenuto 189 punti. Al secondo posto il brano &#8216;I Beagles&#8217; di Claudia Verrillo con 192 punti. Il brano pi\u00f9 cliccato sul sito ufficiale della Rai \u00e8 stato &#8216;Chicopez&#8217; cantato da Ines Rizzo, di 8 anni, che ha vinto il premio web. Un ottimo risultato per Sara, la piccola di Castrolibero che \u00e8 stata molto apprezzata dalla giuria e dai bambini che hanno partecipato all&#8217;evento nell&#8217;Antoniano di Bologna. Si chiude cos\u00ec la 57^ edizione dello Zecchino D&#8217;Oro che quest&#8217;anno ha coinvolto anche un talento calabrese di 10 anni, Sara. La sua canzone parla di speranza; una preghiera, un desiderio che si fa prima di dormire immaginando un mondo migliore, un domani pi\u00f9 sereno.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOLOGNA &#8211; La canzone &#8216;Chi ha paura del buio&#8217; di Edoardo Barchi e Alessia Chianese ha vinto con 199 punti la 57^ edizione dello Zecchino D&#8217;Oro.<\/p>\n","protected":false},"author":22,"featured_media":38482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,565],"tags":[],"class_list":["post-38481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-castrolibero-montalto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=38481"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/38482"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=38481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=38481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=38481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}