{"id":38586,"date":"2014-12-03T08:39:16","date_gmt":"2014-12-03T07:39:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/incidente-mortale-sulla-statale-106-la-vittima-e-un-62enne-di-corigliano\/"},"modified":"2023-01-17T13:01:23","modified_gmt":"2023-01-17T12:01:23","slug":"17073-incidente-mortale-sulla-statale-106-la-vittima-e-un-62enne-di-corigliano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/17073-incidente-mortale-sulla-statale-106-la-vittima-e-un-62enne-di-corigliano\/","title":{"rendered":"Incidente mortale sulla statale 106, la vittima \u00e8 un 62enne di Corigliano"},"content":{"rendered":"<p>ROSSANO (CS) &#8211; Ancora un incidente su quella che viene ribattezzata da sempre la &#8216;statale della morte&#8217;.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un uomo di 62 anni, Mario De Gennaro di Corigliano Calabro ha perso la vita a seguito di un incidente avvenuto a Rossano, sulla statale 106 jonica. L&#8217;uomo era alla guida di una Chevrolet Matiz che si \u00e8 scontrata, per cause in corso di accertamento con una Fiat Panda, guidata da una donna di 32 anni. De Gennaro, \u00e8 stato soccorso e portato in ospedale ma \u00e8 morto poco dopo. La donna invece, ha riportato delle ferite ad un ginocchio. Sul posto per gli accertamenti del caso anche la Polizia Stradale di Trebisacce.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROSSANO (CS) &#8211; Ancora un incidente su quella che viene ribattezzata da sempre la &#8216;statale della morte&#8217;.<\/p>\n","protected":false},"author":19,"featured_media":38587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-38586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=38586"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/38587"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=38586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=38586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=38586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}