{"id":38702,"date":"2014-12-06T14:05:23","date_gmt":"2014-12-06T13:05:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/orgoglio-di-calabria-premiazione\/"},"modified":"2023-01-17T13:01:29","modified_gmt":"2023-01-17T12:01:29","slug":"17133-orgoglio-di-calabria-premiazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/17133-orgoglio-di-calabria-premiazione\/","title":{"rendered":"Degustazione dei vini vincitori del concorso &#8216;Miglior novello del Meridione 2014&#8217;"},"content":{"rendered":"<div dir=\"ltr\">MONTALTO UFFUGO &#8211; Si \u00e8 tenuto ieri sera l&#8217;evento finale dell&#8217;ottava edizione dei Tini di San Martino,<\/div>\n<p>  <!--more-->  <\/p>\n<div dir=\"ltr\">Attraverso una cena &#8211; degustazione sono stati presentati i vincitori del concorso &#8216;Miglior novello del Meridione 2014&#8217; in localit\u00e0 Santa Maria di Settimo presso il ristorante &#8216;Orgoglio di Calabria&#8217;. I partecipanti hanno potuto godere del sapore inconfondibile dei due vincitori ex aequo: Cantina Spadafora di Mangone e Cantina Criser\u00e0 di Reggio Calabria. La serata conclusiva dedicata ai vini del Sud Italia resa possibile dall&#8217;impegno profuso nella realizzazione della tre gionri enologica dal Comune di Cosenza e dalla Provincia di Cosenza \u00e8 stata presenziata dai titolari delle due aziende vincitrici: Ippolito Spadafora e Franco Tramontana. Unico produttore di vino novello della provincia di Cosenza Ippolito Spadafora ha posto l&#8217;accento sul fatto che &#8220;il consumatore ritiene il novello un prodotto di scarsa qualit\u00e0 disconoscendo l&#8217;estremo lavoro necessario alla sua produzione confondendolo spesso con il vino nuovo. E&#8217; un vino su cui la nostra azienda ha sempre creduto dando soddisfazioni a tutti lavoratori che contribuiscono alla sua immissione sul mercato&#8221;. Franco Tramontana ha invece sottolineato l&#8217;importanza &#8220;di avere dei novelli calabresi in una regione geograficamente differente dalle zone in cui si producono vini novelli conosciuti come il San Giovese. Il nostro novello \u00e8 diverso da quello prodotto nel Nord Italia in Francia, \u00e8 corposo, profumato, strutturatto come un vino maturo che si pu\u00f2 consumare con ogni tipo di pietanza, anche con i dessert&#8221;. Al termine della degustazione i due imprenditori sono stati premiati dall&#8217;organizzatore dell&#8217;evento Tommaso Caporale.&nbsp;<\/div>\n<div id=\"yui_3_16_0_1_1417873071696_7907\" dir=\"ltr\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>MONTALTO UFFUGO &#8211; Si \u00e8 tenuto ieri sera l&#8217;evento finale dell&#8217;ottava edizione dei Tini di San Martino,<\/p>\n","protected":false},"author":22,"featured_media":38703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,565],"tags":[],"class_list":["post-38702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-castrolibero-montalto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=38702"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/38702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/38703"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=38702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=38702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=38702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}