{"id":3927,"date":"2012-09-19T07:01:59","date_gmt":"2012-09-19T05:01:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3927"},"modified":"2023-01-17T13:36:59","modified_gmt":"2023-01-17T12:36:59","slug":"1044-cosenza-falsi-provini-hard-per-rimorchiare-una-truffa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1044-cosenza-falsi-provini-hard-per-rimorchiare-una-truffa\/","title":{"rendered":"Cosenza, falsi provini hard per rimorchiare, una truffa"},"content":{"rendered":"<p style=\"text-align: justify;\">COSENZA &#8211; Un trentaseienne cosentino, S. A., finto agente di casting, \u00e8 stato denunciato ieri a Cosenza.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Si spacciava come intermediario di due reali agenzie, la \u201cCasting Italia\u201d (da ventotto anni nel mondo dei casting televisivi, lavora abitualmente con Sky, Mediaset e Rai) e la \u201cCento per Cento Produzioni\u201d, una piccola casa di produzione di film hard amatoriali, rivenduti sul web nel circuito nazionale. I titolari delle due agenzie non hanno idea di chi sia l\u2019uomo, n\u00e9 hanno mai avuto collaboratori in Calabria. Lui, per\u00f2, aveva pubblicato un annuncio di lavoro su svariati siti, lo scorso 12 settembre. La collaboratrice del Quotidiano Aurelia Zucaro lo ha intercettato e smascherato con un filmato.<\/p>\n<p style=\"text-align: justify;\">&nbsp;Il testo dell&#8217;annuncio pubblicato su internet parlava chiaro: \u00abLa &#8220;Casting Italia&#8221;, azienda inserita nel settore della produzione di film hard amatoriali e non, seleziona gratuitamente ragazze e signore dai 19 ai 50 anni per provini simulati, in Cosenza, per la realizzazione di film genere soft porno. Si richiede presenza gradevole e massima seriet\u00e0. I casting, in completa discrezione, si svolgono in Cosenza citt\u00e0 e sono totalmente gratuiti: se ingaggiate, previsti compensi economici molto alti e remunerati con contratti a norma di legge\u00bb.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Gli eventi hanno fatto emergere un imbroglio, perverso e un po\u2019 arrangiato. Aurelia Zucaro si \u00e8 spacciata per aspirante attrice e al telefono l&#8217;uomo le ha spiegato: \u00abCi vediamo nel mio studio a Via Veneto. No, non c\u2019\u00e8 un attore. Siamo solo io e te e una telecamera non professionale. Si deve stare nudi, ovviamente. Ma solo alcune scene sono reali, il resto sono posizioni simulate. Io poi invio il video alla \u201cCento per Cento\u201d e se piaci ti contattano loro. Puoi guadagnare anche 1800 euro a film\u00bb.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Poi lei ha avvisato i carabinieri e si \u00e8 presentata all&#8217;appuntamento con una telecamera nascosta. E per l&#8217;uomo \u00e8 scattata la denuncia a piede libero.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">http:\/\/www.ilquotidianodellacalabria.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Un trentaseienne cosentino, S. A., finto agente di casting, \u00e8 stato denunciato ieri a Cosenza.<\/p>\n","protected":false},"author":22,"featured_media":1776,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-3927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3927"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/1776"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}