{"id":39370,"date":"2014-02-15T11:52:43","date_gmt":"2014-02-15T10:52:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/primarie-pd-domani-si-vota-in-calabria-ecco-i-candidati-2\/"},"modified":"2023-01-17T13:02:12","modified_gmt":"2023-01-17T12:02:12","slug":"32668-primarie-pd-domani-si-vota-in-calabria-ecco-i-candidati-2","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/32668-primarie-pd-domani-si-vota-in-calabria-ecco-i-candidati-2\/","title":{"rendered":"Primarie PD: domani si vota in Calabria, ecco i candidati"},"content":{"rendered":"<p>COSENZA &#8211; I democrat calabresi chiamati ad eleggere il nuovo segretario regionale.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il Pd riconvoca i suoi elettori ai seggi dopo l\u2019appuntamento dello scorso 8 dicembre che ha incoronato Matteo Renzi leader nazionale del partito. Domenica 16 febbraio si celebrano infatti le primarie per la segreteria in 16 regioni. Vanno al voto l\u2019Alto Adige, la Valle d\u2019Aosta, il Friuli-Venezia Giulia, il Veneto, il Piemonte, la Lombardia, la Liguria, la Toscana, le Marche, l\u2019Umbria, il Lazio, il Molise, la Puglia, la Campania, la Calabria e la Sicilia. Dopo lo strappo interno sul governo, che ha portato alle dimissioni di Enrico Letta e alla staffetta con il sindaco di Firenze, il Partito democratico \u00e8 quindi chiamato a gestire l\u2019elezione dei leader locali. La chiamata ai seggi &nbsp;\u00e8 passata piuttosto in sordina rispetto alle ultime consultazioni sebbene si preveda che i cittadini al voto saranno molti, molti di meno.<\/p>\n<p>&nbsp;<\/p>\n<p>Alle primarie regionali del Pd potranno votare tutti: anche chi non \u00e8 tesserato al partito. Per esprimere la propria preferenza baster\u00e0 dichiarare di aderire alla proposta politica del Partito democratico &nbsp;e versare i 2 euro di contributo per l\u2019organizzazione. Tutti, anche i tesserati, dovranno presentarsi al gazebo con il certificato elettorale e un documento di identit\u00e0. I minori dai 16 ai 18 anni potranno registrarsi al seggio al momento del voto, lo stesso vale per i migranti con regolare permesso di soggiorno. L\u2019esito del voto dovrebbe essere ufficiale in tarda serata. I candidati in Calabria sono quattro: Massimo Canale, Domenico Lo Polito, Ernesto Magorno e Bruno Vilella.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Massimo Canale<\/strong>: &#8220;Il Pd che dobbiamo mettere in piedi a partire dal 17 Febbraio &#8211; afferma il candidato alla segreteria regionale Canale &#8211; deve essere un partito che innanzitutto conosca la Calabria, che sia pi\u00f9 vicino ai circoli, ai cittadini e agli amministratori locali. Il mio programma viene scritto man mano che incontro le persone e affrontiamo insieme i temi caldi come la questione rifiuti, ad esempio, sono loro che spiegano quali sono le proprie esigenze e noi ne facciamo tesoro. L&#8217;esperienza sul campo ci ha permesso di incontrare e conoscere la gente e dare risposte al territorio&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Domenico Lo Polito<\/strong>: &#8220;Mi sono candidato &#8211; dichiara Lo Polito &#8211; perch\u00e8 ritengo che bisogna costruire in Calabria un Partito Democratico che parta dalla base. Bisogna cambiare il metodo, non pi\u00f9 vertici nazionali che decidono, ma la base. Un sistema che non ha funzionato perch\u00e8 per anni in Calabria il partito \u00e8 stato commissariato, molte sezioni non sono esistite per diverso tempo e quando siamo stati al governo della Regione non abbiamo raggiunto i risultati sperati. Noi crediamo nei processi che vengono dal basso perch\u00e8 solo cos\u00ec si pu\u00f2 essere vicini ai bisogni reali dei cittadini e dei territori. La proposta politica deve venire dalla gente e dalle sue esigenze. Vogliamo essere solo esecutori della volont\u00e0 del popolo. Con persone nuove&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ernesto Magorno<\/strong>: &#8220;La mia proposta &#8211; spiega il candidato Magorno &#8211; \u00e8 quella di ascoltare i calabresi, il mondo della ricerca, del lavoro, dell&#8217;universit\u00e0, della cultura, delle imprese. Con loro dobbiamo formulare proposte per costruire un grande progetto per ricostruire il programma per la nostra Regione e conquistare il governo della Calabria. Non ho la presunzione di dire che ho una proposta dico che dovremmo guardare al segretario nazionale Matteo Renzi. SErve un uomo nuovo &nbsp;per rinnovare la proposta politica. Una personalit\u00e0 di rilievo che sappia proporre il vero cambiamento&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Bruno Vilella<\/strong>: &#8220;Il patto che stiamo cercando di stringere con i calabresi &#8211; secondo il candidato alla segreteria calabra Vilella &#8211; \u00e8 quello di imprimere una svolta in direzione del rinnovamento della classa politica. In Calabria la crisi \u00e8 pi\u00f9 pressante che altrove. C&#8217;\u00e8 quindi bisogno di un ricambio per accellerare un vero e proprio processo di restyling della classe dirigente. La discontinuit\u00e0 con la classe politica precedente deve essere evidente. Dobbiamo rompere i vecchi sistemi che governano le cariche pi\u00f9 alte della nostra Regione per dare un po&#8217; d&#8217;ossigeno alla Calabria. Un obiettivo ambizioso, ma alla portata di chi vuole essere al fianco dei calabresi. Ci vuole una grande apertura democratica agli altri partiti in Calabria per farla divenire una Regione efficiente e non ricettacolo di truffe e roberie&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; I democrat calabresi chiamati ad eleggere il nuovo segretario regionale.<\/p>\n","protected":false},"author":22,"featured_media":30407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-39370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/39370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=39370"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/39370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30407"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=39370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=39370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=39370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}