{"id":3945,"date":"2012-09-19T10:35:09","date_gmt":"2012-09-19T08:35:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3945"},"modified":"2023-01-17T13:37:01","modified_gmt":"2023-01-17T12:37:01","slug":"1063-svezia-primo-trapianto-di-utero-da-madri-a-figlie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1063-svezia-primo-trapianto-di-utero-da-madri-a-figlie\/","title":{"rendered":"Svezia, primo trapianto di utero da madri a figlie"},"content":{"rendered":"<p><span style=\"color: #6f6f6f; font-family: Arial, 'Trebuchet MS', sans-serif; font-size: 12px; line-height: 17px; background-color: #ffffff;\">(AGI) &#8211; STOCCOLMA &#8211; Due donne svedesi hanno ricevuto un trapianto di utero dalle loro madri, che potrebbe permettere loro di avere una gravidanza. Lo ha annunciato l&#8217;ospedale della Sweden University di Goteborg, secondo cui la procedura potrebbe essere ripetuta entro fine anno su altre otto donne.<\/span><br style=\"font-family: Arial, 'Trebuchet MS', sans-serif; margin: 0px; padding: 0px; border: 0px; outline: none; list-style-type: none; color: #6f6f6f; line-height: 17px; background-color: #ffffff;\" \/><span style=\"color: #6f6f6f; font-family: Arial, 'Trebuchet MS', sans-serif; font-size: 12px; line-height: 17px; background-color: #ffffff;\">&nbsp; Entrambe le donne hanno piu&#8217; di 30 anni, spiega il comunicato dell&#8217;ospedale. Una ha avuto l&#8217;asportazione dell&#8217;utero e delle ovaie a causa di un tumore della cervice, mentre l&#8217;altra e&#8217; nata senza l&#8217;organo per una malformazione congenita. Entrambe hanno gia&#8217; iniziato da tempo le procedure per la fertilizzazione in vitro, e dopo un anno di osservazione, se non si verificheranno problemi, riceveranno gli embrioni che ora hanno congelato. &#8220;Le donne donatrici stanno bene, camminano e verranno dimesse in pochi giorni &#8211; ha spiegato Mats Brannstrom, uno dei 10 autori dell&#8217;intervento &#8211; ma solo se le riceventi riusciranno ad avere figli considereremo l&#8217;intervento un successo&#8221;. Il progetto per il trapianto e&#8217; in corso dal 1999. E&#8217; la prima volta al mondo che si effettua un intervento simile, mentre lo scorso anno in Turchia un utero e&#8217; stato trapiantato ma da una donatrice deceduta. Nel 2000 in Arabia saudita era stata tentata un&#8217;operazione simile, ma dopo tre mesi l&#8217;utero e&#8217; stato rimosso per un coagulo. (AGI)&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(AGI) &#8211; STOCCOLMA &#8211; Due donne svedesi hanno ricevuto un trapianto di utero dalle loro madri, che potrebbe permettere loro di avere una gravidanza. Lo ha annunciato l&#8217;ospedale della Sweden University di Goteborg, secondo cui la procedura potrebbe essere ripetuta entro fine anno su altre otto donne.&nbsp; Entrambe le donne hanno piu&#8217; di 30 anni, [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":1812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34,5,52],"tags":[],"class_list":["post-3945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine","category-old","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3945"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/1812"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}