{"id":39539,"date":"2015-01-05T13:41:37","date_gmt":"2015-01-05T12:41:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/terremoto-in-sila-scossa-avvertita-nel-crotonese\/"},"modified":"2023-01-17T12:31:00","modified_gmt":"2023-01-17T11:31:00","slug":"17525-terremoto-in-sila-scossa-avvertita-nel-crotonese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/17525-terremoto-in-sila-scossa-avvertita-nel-crotonese\/","title":{"rendered":"Terremoto in Sila, scossa avvertita nel crotonese"},"content":{"rendered":"<p>BELVEDERE SPINELLO (KR) &#8211; L&#8217;epicentro \u00e8 stato individuato nei pressi dei Comuni di Belvedere Spinello e Roccabernarda.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un terremoto di magnitudo 2.3 \u00e8 avvenuto alle ore 14:06 di oggi. Il sisma \u00e8 stato localizzato dalla Rete Sismica Nazionale dell&#8217;INGV nel distretto sismico della Sila. A seguito delle scosse non sono stati segnalati danni a cose o persone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BELVEDERE SPINELLO (KR) &#8211; L&#8217;epicentro \u00e8 stato individuato nei pressi dei Comuni di Belvedere Spinello e Roccabernarda.<\/p>\n","protected":false},"author":22,"featured_media":39540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-39539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/39539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=39539"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/39539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/39540"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=39539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=39539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=39539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}