{"id":39874,"date":"2015-01-15T14:38:33","date_gmt":"2015-01-15T13:38:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/stalking-perseguita-ex-moglie-sottoposto-divieto-avvicinarsi\/"},"modified":"2023-01-17T12:31:19","modified_gmt":"2023-01-17T11:31:19","slug":"17704-stalking-perseguita-ex-moglie-sottoposto-divieto-avvicinarsi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/17704-stalking-perseguita-ex-moglie-sottoposto-divieto-avvicinarsi\/","title":{"rendered":"Stalker 41enne perseguita l&#8217;ex moglie, ma le telecamere lo immortalano"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Il provvedimento \u00e8 stato emsso a seguito delle&nbsp;indagini svolte dai carabinieri.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un uomo di 41 anni \u00e8 stato sottoposto al divieto di avvicinarsi ai luoghi frequentati dall&#8217;ex moglie. Il provvedimento \u00e8 stato emesso dal giudice del tribunale di Vibo Valentia. L&#8217;uomo, originario di Pizzo Calabro, nonostante la separazione, continuava a perseguitare l&#8217;ex moglie con minacce e aggressioni fisiche. A richiedere la misura cautelare sono stati i carabinieri. Ad incastrare il quarantunenne anche alcune telecamere che l&#8217;hanno ripreso mentre perseguitava la donna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Il provvedimento \u00e8 stato emsso a seguito delle&nbsp;indagini svolte dai carabinieri.&nbsp;<\/p>\n","protected":false},"author":22,"featured_media":39875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-39874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/39874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=39874"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/39874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/39875"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=39874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=39874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=39874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}