{"id":4006,"date":"2012-09-20T09:08:37","date_gmt":"2012-09-20T07:08:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4006"},"modified":"2023-01-17T13:37:08","modified_gmt":"2023-01-17T12:37:08","slug":"1132-inchiesta-minotauro-gdf-sequestra-108-immobili-tra-piemonte-e-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1132-inchiesta-minotauro-gdf-sequestra-108-immobili-tra-piemonte-e-calabria\/","title":{"rendered":"&#8220;Minotauro&#8221;, sequestrati 108 immobili tra Piemonte e Calabria"},"content":{"rendered":"<p style=\"text-align: justify;\">(Adnkronos) &#8211; Centootto immobili appartenenti a 38 imputati di associazione a delinquere di stampo mafioso nell&#8217;ambito dell&#8217;inchiesta &#8216;Minotauro&#8221;, sono stati sequestrati, in Piemonte ed in Calabria, dalla Guardia di Finanza torinese. I beni, 41 abitazioni, 40 terreni e 27 autorimesse, serviranno a garantire il pagamento delle spese processuali, per oltre 3 milioni di euro nei quattro anni di durata delle indagini. Un patrimonio che le Fiamme Gialle, coordinate dal Gruppo Riciclaggio della Procura torinese, hanno sequestrato per garantire il rimborso delle spese dell&#8217;intero procedimento. Altri sequestri della stessa natura sono stati effettuati dalla Direzione investigativa antimafia.<\/p>\n<p style=\"text-align: justify;\">I provvedimenti di sequestro conservativo sono stati emessi a un anno di distanza dal blitz del giugno 2011 e in concomitanza con la richiesta di rinvio a giudizio di 169 indagati, la maggior parte dei quali per il reato di associazione a delinquere di stampo mafioso. Le unita&#8217; immobiliari individuate e sequestrate dai finanzieri del Nucleo di Polizia Tributaria, concorreranno a coprire le spese gia&#8217; sostenute e quelle ancora da sostenere in tutte le fasi del procedimento per un prevedibile ammontare che raggiungera&#8217; i 3 milioni di euro: costo delle intercettazioni telefoniche e delle indagini tecniche effettuate per quattro anni dalla Dda della Procura, spese per la detenzione in carcere, oneri connessi alla gestione dei beni gia&#8217; sequestrati e spese processuali. Cosi&#8217;, alla vigilia della prima udienza, fissata per il prossimo 18 ottobre, e&#8217; stato posto un altro importante punto fermo: se, al termine del processo, i soggetti condannati dovessero risultare insolventi, il patrimonio sequestrato potra&#8217; essere definitivamente confiscato e posto in vendita. Il ricavato servira&#8217; a coprire le spese di giustizia sostenute, evitando cosi&#8217; &#8221;ricadute&#8221; negative sul bilancio dello Stato e quindi sulla collettivita&#8217;.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Adnkronos) &#8211; Centootto immobili appartenenti a 38 imputati di associazione a delinquere di stampo mafioso nell&#8217;ambito dell&#8217;inchiesta &#8216;Minotauro&#8221;, sono stati sequestrati, in Piemonte ed in Calabria, dalla Guardia di Finanza torinese. I beni, 41 abitazioni, 40 terreni e 27 autorimesse, serviranno a garantire il pagamento delle spese processuali, per oltre 3 milioni di euro nei [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":1933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17,5],"tags":[],"class_list":["post-4006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4006"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/1933"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}