{"id":4013,"date":"2012-09-20T09:51:53","date_gmt":"2012-09-20T07:51:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4013"},"modified":"2023-01-17T13:37:08","modified_gmt":"2023-01-17T12:37:08","slug":"1139-speranza-da-il-benvenuto-al-nuovo-presidente-del-tribunale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1139-speranza-da-il-benvenuto-al-nuovo-presidente-del-tribunale\/","title":{"rendered":"Speranza d\u00e0 il benvenuto al nuovo Presidente del Tribunale"},"content":{"rendered":"<p style=\"text-align: justify;\">LAMEZIA(CZ) &#8211; Il sindaco di Lamezia Terme, Gianni Speranza, recandosi in Tribunale, ha dato il benvenuto, in occasione del suo insediamento, al nuovo presidente del Tribunale, Bruno Brattoli. <br \/>Il sindaco, nell&#8217;accoglierlo in citt\u00e0 e portagli il saluto dell&#8217;Amministrazione comunale e di tutti i lametini e nell&#8217;augurargli buon lavoro, ha espresso la soddisfazione dell&#8217;intera comunit\u00e0 perch\u00e9 \u201cil successo della battaglia condotta nei mesi scorsi a tutela e salvaguardia dei nostri uffici giudiziari ci ha consentito oggi di festeggiare insieme il suo insediamento\u201d. Il sindaco infine ha colto l&#8217;occasione per ringraziare il dottor Giuseppe Spadaro, presidente della sezione pensale del Tribunale, e ha confermato l&#8217;impegno suo e dell&#8217;Amministrazione a continuare nella proficua collaborazione avviata per l&#8217;affermazione della legalit\u00e0 a Lamezia e nel suo comprensorio.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Strill.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAMEZIA(CZ) &#8211; Il sindaco di Lamezia Terme, Gianni Speranza, recandosi in Tribunale, ha dato il benvenuto, in occasione del suo insediamento, al nuovo presidente del Tribunale, Bruno Brattoli. Il sindaco, nell&#8217;accoglierlo in citt\u00e0 e portagli il saluto dell&#8217;Amministrazione comunale e di tutti i lametini e nell&#8217;augurargli buon lavoro, ha espresso la soddisfazione dell&#8217;intera comunit\u00e0 perch\u00e9 [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":1947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-4013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4013"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/1947"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}