{"id":40144,"date":"2015-01-24T09:04:30","date_gmt":"2015-01-24T08:04:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ultim-ora-continua-la-protesta-selvaggia-del-consorzio-autolinee-bus-in-corteo-per-la-citta\/"},"modified":"2023-01-17T12:31:36","modified_gmt":"2023-01-17T11:31:36","slug":"17844-ultim-ora-continua-la-protesta-selvaggia-del-consorzio-autolinee-bus-in-corteo-per-la-citta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/17844-ultim-ora-continua-la-protesta-selvaggia-del-consorzio-autolinee-bus-in-corteo-per-la-citta\/","title":{"rendered":"ULTIM&#8217;ORA &#8211; Continua la protesta &#8216;selvaggia&#8217; del Consorzio Autolinee. Bus in corteo per la citt\u00e0"},"content":{"rendered":"<p>COSENZA &#8211; Dopo il blocco attuato ieri subito dopo il ponte di Campagnano, la protesta degli autisti del consorzio Autolinee si \u00e8 spostata questa mattina anche all&#8217;autostazione di Cosenza dove la circolazione \u00e8 rimasta bloccata per circa un&#8217;ora.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>Pare che in questi minuti la protesta si stia spostando in giro per la citt\u00e0 dove gli autisti degli autobus del Consorzio Autolinee, improvviseranno blocchi spontanei a Cosenza e nell&#8217;hinterland, provocando di conseguenza rallentamenti e code. La protesta \u00e8 sempre attuata contro il nuovo servizio dell&#8217;A.M.A.C.O, ovvero la circolare veloce rossa attivata da pochi giorni e che collega Cosenza all&#8217;Universit\u00e0 della Calabria ritenuto dal Consorzio, irregolare e abusivo. Ieri la protesta di decine di autobus del Consorzio ha provocato notevoli disagi sul tratto della statale 19, nei pressi del centro commerciale Metropolis. Mentre proprio questa mattina il sidaco di Cosenza Occhiuto aveva ribadito che il servizio della Circolare Veloce non si fermer\u00e0 davanti nessuna protesta. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Dopo il blocco attuato ieri subito dopo il ponte di Campagnano, la protesta degli autisti del consorzio Autolinee si \u00e8 spostata questa mattina anche all&#8217;autostazione di Cosenza dove la circolazione \u00e8 rimasta bloccata per circa un&#8217;ora.&nbsp;<\/p>\n","protected":false},"author":22,"featured_media":40145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-40144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=40144"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/40145"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=40144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=40144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=40144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}