{"id":40265,"date":"2015-01-28T15:15:13","date_gmt":"2015-01-28T14:15:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/neve-e-maltempo-anche-il-sindaco-di-rende-marcello-manna-chiude-le-scuole-per-domani\/"},"modified":"2023-01-17T12:31:43","modified_gmt":"2023-01-17T11:31:43","slug":"17906-neve-e-maltempo-anche-il-sindaco-di-rende-marcello-manna-chiude-le-scuole-per-domani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/17906-neve-e-maltempo-anche-il-sindaco-di-rende-marcello-manna-chiude-le-scuole-per-domani\/","title":{"rendered":"Neve e maltempo: anche il sindaco di Rende, Marcello Manna, chiude le scuole per domani"},"content":{"rendered":"<p>RENDE (CS) &#8211; Anche il primo cittadino di Rende ha emesso, nel primo pomeriggio, un&#8217;ordinanza per la chiusura delle scuole su tutto il territorio comunale di Rende.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Dopo Cosenza, anche Rende chiude domani le scuole per la neve. Pochi minuti fa, il primo cittadino Marcello Manna, ha mandato in esecuzione un&#8217;ordinanza che riguarda la  chiusura di tutti i plessi scolastici, compresi gli uffici, delle Scuole dell&#8217;Infanzia, Primarie, Secondarie di 1^ Grado (Medie) e Secondarie di 2^ Grado (Superiori) per il giorno di gioved\u00ec 29 gennaio 2015 e dispone che la presente ordinanza sia immediatamente notificata ai dirigenti scolastici interessati, al Comando di Polizia Municipale e alla societ\u00e0 Rende Servizi, responsabile del Trasporto Scolastico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE (CS) &#8211; Anche il primo cittadino di Rende ha emesso, nel primo pomeriggio, un&#8217;ordinanza per la chiusura delle scuole su tutto il territorio comunale di Rende.<\/p>\n","protected":false},"author":23,"featured_media":40266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,565],"tags":[],"class_list":["post-40265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-castrolibero-montalto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=40265"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/40266"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=40265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=40265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=40265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}